{"id":12385,"date":"2024-03-28T11:12:31","date_gmt":"2024-03-28T10:12:31","guid":{"rendered":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/?page_id=12385"},"modified":"2024-05-02T08:23:39","modified_gmt":"2024-05-02T06:23:39","slug":"hochzeitsfotograf-langwieder-see","status":"publish","type":"page","link":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/","title":{"rendered":"Hochzeitsfotograf Langwieder See \u2013 Die Kunst der emotionalen Bildsprache"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light has-parallax has-custom-content-position is-position-bottom-center has-ast-global-color-5-color has-text-color has-link-color has-small-font-size wp-elements-ebc7777d38c9c7a1190243f53e678157\" style=\"border-style:none;border-width:0px;border-radius:0px;margin-top:0;margin-bottom:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;min-height:100vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><div role=\"img\" aria-label=\"Hochzeitsfotograf Langwieder See\" class=\"wp-block-cover__image-background wp-image-10192 has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/whiteandlight.com\/wp-content\/uploads\/hochzeitsfotograf-muenchen-emitionen-hochzeitsfotos-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-in-muenchen-ungestellt-natuerlich-jpg.webp)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-flow wp-container-core-cover-is-layout-e603688c wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-6cba958f\" id=\"hochzeitsfotografie-Langwieder See\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-28258681\"><h1 class=\"uagb-heading-text\">Hochzeitsfotograf Langwieder See<\/h1><\/div>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-3a853490 uagb-columns__columns-3 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-8969bd6f\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-5780da15\"><div class=\"uagb-column__overlay\"><\/div>\n<p>Hi, ich bin Andrej, Ihr Hochzeitsfotograf am Langwieder See. Die Liebe und die Freude, die ich bei Hochzeiten erlebe, inspirieren mich immer wieder aufs Neue. Genau diese Inspiration war es, die mich zur Hochzeitsfotografie und zur Gr\u00fcndung von \u201eWhite and Light \u2013 Hochzeitsfotografie\u201c gef\u00fchrt hat. Es ist mir eine gro\u00dfe Ehre, Brautpaare an ihrem Hochzeitstag am Langwieder See und Umland fotografisch zu begleiten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default\"><img data-dominant-color=\"727272\" data-has-transparency=\"false\" style=\"--dominant-color: #727272;\" decoding=\"async\" width=\"800\" height=\"492\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_foto-jpg.webp\" alt=\"Hochzeitsfotograf am Langwieder See \u2013 Andrej\" class=\"wp-image-10236 not-transparent\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_foto-jpg.webp 800w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_foto-768x472.webp 768w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_foto-500x308.webp 500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8a1aceaa\"><h2 class=\"uagb-heading-text\">Hi, ich bin Andrej, Ihr Fotograf am Langwieder See<\/h2><p class=\"uagb-desc-text\">Ausgebildeter Fotograf und Dipl. Grafik-Designer<\/p><\/div>\n\n\n\n<p>Mit meiner Kamera fange ich die Freude des Ja-Worts, die z\u00e4rtlichen Blicke und die ausgelassene Stimmung der Hochzeitsfeier ein. Dabei arbeite ich stets diskret und professionell, um den Ablauf des Tages nicht zu st\u00f6ren. Seit 15 Jahren bin ich als Hochzeitsfotograf am Langwieder See und Umland t\u00e4tig und habe unz\u00e4hlige gl\u00fcckliche Paare an ihrem sch\u00f6nsten Tag begleitet. Meine Erfahrung und Leidenschaft f\u00fcr die Fotografie garantieren Ihnen hochwertige Bilder, die Sie ein Leben lang an Ihre Hochzeit erinnern werden.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size has-medium-font-size\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/#kontaktformular\">UNVERBINDLICH ANFRAGEN<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-b0070f0e\"><div class=\"uagb-column__overlay\"><\/div>\t\t\t\t<div class=\"wp-block-uagb-table-of-contents uagb-toc__align-left uagb-toc__columns-1  uagb-block-0f9a2ccc      \"\n\t\t\t\t\tdata-scroll= \"\"\n\t\t\t\t\tdata-offset= \"30\"\n\t\t\t\t\tstyle=\"\"\n\t\t\t\t>\n\t\t\t\t<div class=\"uagb-toc__wrap\">\n\t\t\t\t\t\t<div class=\"uagb-toc__title\">\n\t\t\t\t\t\t\tSEITENINHALT\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uagb-toc__list-wrap \">\n\t\t\t\t\t\t<ol class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#hi-ich-bin-andrej-ihr-fotograf-am-langwieder-see\" class=\"uagb-toc-link__trigger\">Hi, ich bin Andrej, Ihr Fotograf am Langwieder See<\/a><li class=\"uagb-toc__list\"><a href=\"#einblicke-in-meine-hochzeitsreportagen-hochzeitsfotograf-langwieder-see\" class=\"uagb-toc-link__trigger\">Einblicke in meine Hochzeitsreportagen | Hochzeitsfotograf Langwieder See<\/a><li class=\"uagb-toc__list\"><a href=\"#hochzeitspakethochzeitsfotograf-langwieder-see\" class=\"uagb-toc-link__trigger\">HochzeitspaketHochzeitsfotograf Langwieder See<\/a><li class=\"uagb-toc__list\"><a href=\"#ein-blick-hinter-die-kulissen-von-wl-hochzeitsfotograf-langwieder-see\" class=\"uagb-toc-link__trigger\">Ein Blick hinter die Kulissen von W&amp;L \u2013 Hochzeitsfotograf Langwieder See<\/a><li class=\"uagb-toc__list\"><a href=\"#hochzeitspaare-\u00fcber-wl-hochzeitsfotograf-langwieder-see\" class=\"uagb-toc-link__trigger\">Hochzeitspaare \u00fcber W&amp;L &#8211; Hochzeitsfotograf Langwieder See<\/a><li class=\"uagb-toc__list\"><a href=\"#von-der-buchung-bis-zur-bild\u00fcbergabe-hochzeitsfotograf-langwieder-see-so-einfach-ist-es\" class=\"uagb-toc-link__trigger\">Von der Buchung bis zur Bild\u00fcbergabe: Hochzeitsfotograf Langwieder See \u2013 So einfach ist es!<\/a><li class=\"uagb-toc__list\"><a href=\"#suchen-sie-einen-fotografen-am-langwieder-see\" class=\"uagb-toc-link__trigger\">Suchen Sie einen Fotografen am Langwieder See?<\/a><li class=\"uagb-toc__list\"><a href=\"#kontaktformular\" class=\"uagb-toc-link__trigger\">Kontaktformular<\/a><li class=\"uagb-toc__list\"><a href=\"#instagram-wl-hochzeitsfotograf-langwieder-see\" class=\"uagb-toc-link__trigger\">Instagram W&amp;L \u2013 Hochzeitsfotograf Langwieder See<\/a><li class=\"uagb-toc__list\"><a href=\"#tipps-f\u00fcr-unvergessliche-hochzeitsfotos-von-fotograf-langwieder-see\" class=\"uagb-toc-link__trigger\">Tipps f\u00fcr unvergessliche Hochzeitsfotos von fotograf Langwieder See<\/a><\/ol>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-ce3f5011 uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-3d8910e0\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-8de1164e wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-fotoshooting-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-fotoshooting-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-fotoshooting-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-fotoshooting-jpg.webp\" alt=\"Kirchliche Hochzeit - Langwieder See\" class=\"uag-image-11092\" width=\"1180\" height=\"708\" title=\"Kirchliche Hochzeit - Langwieder See\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-e6eb2075 uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-1d61e137\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-37a45a81 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-bester-hochzeitsfotograf-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-bester-hochzeitsfotograf-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-bester-hochzeitsfotograf-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-bester-hochzeitsfotograf-jpg.webp\" alt=\"Hochzeitsfotograf Schloss\" class=\"uag-image-11089\" width=\"1180\" height=\"708\" title=\"Hochzeitsfotograf Schloss\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-00122180 uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-92114a47\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-a93e4c7d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-in-der-naehe-1-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-in-der-naehe-1-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-in-der-naehe-1-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-in-der-naehe-1-jpg.webp\" alt=\"Hochzeitsauto am Langwieder See \u2013 Hochzeitsfotograf Langwieder See\" class=\"uag-image-11150\" width=\"1180\" height=\"787\" title=\"Hochzeitsauto am Langwieder See \u2013 Hochzeitsfotograf Langwieder See\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-dd5f852c uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-f67ca210\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-05d8eb34 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfoto_muenchen-hochzeitsfotografie-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfoto_muenchen-hochzeitsfotografie-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfoto_muenchen-hochzeitsfotografie-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfoto_muenchen-hochzeitsfotografie-jpg.webp\" alt=\"Braut mit Brautstrau\u00df - Kirchliche Hochzeit - Langwieder See\" class=\"uag-image-11086\" width=\"1180\" height=\"708\" title=\"Braut mit Brautstrau\u00df - Kirchliche Hochzeit - Langwieder See\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-a0b0667a uagb-columns__columns-2 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-8c2496ee\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-e14388f6 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-bayern-heiraten-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-bayern-heiraten-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-bayern-heiraten-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-bayern-heiraten-jpg.webp\" alt=\"Hochzeitsfotograf Langwieder See Bayern Heiraten\" class=\"uag-image-11088\" width=\"580\" height=\"870\" title=\"Hochzeitsfotograf Langwieder See Bayern Heiraten\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-9f4c48cb\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-7cc3264c wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-hochzeit-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-hochzeit-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-hochzeit-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-hochzeit-jpg.webp\" alt=\"Hochzeit Langwieder See\" class=\"uag-image-11095\" width=\"580\" height=\"870\" title=\"Hochzeit Langwieder See\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-99497cb5 uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-01f5d589\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-5a114f3d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-heiraten-standesamt-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-heiraten-standesamt-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-heiraten-standesamt-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-heiraten-standesamt-jpg.webp\" alt=\"Hochzeitsfotograf Langwieder See und  Umgebung\" class=\"uag-image-11119\" width=\"2500\" height=\"1500\" title=\"Hochzeitsfotograf Langwieder See und  Umgebung\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-e1ea5dcb uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-f01ec120\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-23fabeaa wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-heiraten-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-heiraten-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-heiraten-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-heiraten-jpg.webp\" alt=\"Heiraten in Standesamt Langwieder See\" class=\"uag-image-11087\" width=\"1180\" height=\"708\" title=\"Heiraten in Standesamt Langwieder See\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-8fcd27ae uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-ca438040\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-21395a7f wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-hochzeitsfotografie-1-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-hochzeitsfotografie-1-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-hochzeitsfotografie-1-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-hochzeitsfotografie-1-jpg.webp\" alt=\"Ihr Fotograf in Standesamt\" class=\"uag-image-11149\" width=\"1180\" height=\"787\" title=\"Ihr Fotograf in Standesamt\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-589377f9 uagb-columns__columns-2 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-6f503494\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-af302930 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-tips-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-tips-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-tips-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-tips-jpg.webp\" alt=\"Paarshooting \u2013 Fotograf in Langwieder See\" class=\"uag-image-11100\" width=\"580\" height=\"870\" title=\"Paarshooting \u2013 Fotograf in Langwieder See\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-2580d696\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-6020b9b7 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-boho-1-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-boho-1-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-boho-1-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-boho-1-jpg.webp\" alt=\"Fotograf in Standesamt Langwieder See \u2013 Boho style\" class=\"uag-image-11147\" width=\"580\" height=\"870\" title=\"Fotograf in Standesamt Langwieder See \u2013 Boho style\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-c53973f4 uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-71da0743\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-445d1a62 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-umgebung-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-umgebung-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-umgebung-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-umgebung-jpg.webp\" alt=\"Fotograf in Standesamt, Langwieder See, M\u00fcnchen\" class=\"uag-image-11101\" width=\"1180\" height=\"708\" title=\"Fotograf in Standesamt, Langwieder See, M\u00fcnchen\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-2da0f1f8 uagb-columns__columns-2 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-c3669a58\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-85d44d4a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-kosten-hochzeitsfotografie-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-kosten-hochzeitsfotografie-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-kosten-hochzeitsfotografie-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-kosten-hochzeitsfotografie-jpg.webp\" alt=\"Hochzeitsfotograf Langwieder See Kosten Hochzeitsfotografie\" class=\"uag-image-11098\" width=\"580\" height=\"870\" title=\"Hochzeitsfotograf Langwieder See Kosten Hochzeitsfotografie\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-015eb386\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-bc614044 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-fotograf-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-fotograf-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-fotograf-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-fotograf-jpg.webp\" alt=\"Fotograf Boho style Langwieder See\" class=\"uag-image-11091\" width=\"580\" height=\"870\" title=\"Fotograf Boho style Langwieder See\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-183da41b uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-9b173bcb\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-f033b423 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-facebook-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-facebook-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-facebook-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-facebook-jpg.webp\" alt=\"Hochzeitsfotograf Langwieder See\" class=\"uag-image-11090\" width=\"1180\" height=\"787\" title=\"Hochzeitsfotograf Langwieder See\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-08249a1d uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-8bdfcf93\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-9d4235e1 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-preise-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-preise-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-preise-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-preise-jpg.webp\" alt=\"Preise \u2013 Fotograf am Langwieder See\" class=\"uag-image-11099\" width=\"1180\" height=\"708\" title=\"Preise \u2013 Fotograf am Langwieder See\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-5d07860f uagb-columns__columns-1 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-7cba0af0\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-8e06d8b2 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-guenstig-1-jpg.webp ,https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-guenstig-1-jpg.webp 780w, https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-guenstig-1-jpg.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-muenchen-guenstig-1-jpg.webp\" alt=\"Hochzeitsfotograf G\u00fcnstig Langwieder See\" class=\"uag-image-11148\" width=\"1180\" height=\"787\" title=\"Hochzeitsfotograf G\u00fcnstig Langwieder See\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<div class=\"wp-block-uagb-social-share uagb-social-share__outer-wrap uagb-social-share__layout-horizontal uagb-block-fccfb223\">\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-71408164\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/pinterest.com\/pin\/create\/link\/?url=\" tabindex=\"0\" role=\"button\" aria-label=\"pinterest\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M448 80v352c0 26.5-21.5 48-48 48H154.4c9.8-16.4 22.4-40 27.4-59.3 3-11.5 15.3-58.4 15.3-58.4 8 15.3 31.4 28.2 56.3 28.2 74.1 0 127.4-68.1 127.4-152.7 0-81.1-66.2-141.8-151.4-141.8-106 0-162.2 71.1-162.2 148.6 0 36 19.2 80.8 49.8 95.1 4.7 2.2 7.1 1.2 8.2-3.3 .8-3.4 5-20.1 6.8-27.8 .6-2.5 .3-4.6-1.7-7-10.1-12.3-18.3-34.9-18.3-56 0-54.2 41-106.6 110.9-106.6 60.3 0 102.6 41.1 102.6 99.9 0 66.4-33.5 112.4-77.2 112.4-24.1 0-42.1-19.9-36.4-44.4 6.9-29.2 20.3-60.7 20.3-81.8 0-53-75.5-45.7-75.5 25 0 21.7 7.3 36.5 7.3 36.5-31.4 132.8-36.1 134.5-29.6 192.6l2.2 .8H48c-26.5 0-48-21.5-48-48V80c0-26.5 21.5-48 48-48h352c26.5 0 48 21.5 48 48z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-58e2cd2d\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/www.facebook.com\/sharer.php?u=\" tabindex=\"0\" role=\"button\" aria-label=\"facebook\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.8 90.69 226.4 209.3 245V327.7h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.3 482.4 504 379.8 504 256z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-d7381ce6\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/twitter.com\/share?url=\" tabindex=\"0\" role=\"button\" aria-label=\"twitter\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zm-48.9 158.8c.2 2.8 .2 5.7 .2 8.5 0 86.7-66 186.6-186.6 186.6-37.2 0-71.7-10.8-100.7-29.4 5.3 .6 10.4 .8 15.8 .8 30.7 0 58.9-10.4 81.4-28-28.8-.6-53-19.5-61.3-45.5 10.1 1.5 19.2 1.5 29.6-1.2-30-6.1-52.5-32.5-52.5-64.4v-.8c8.7 4.9 18.9 7.9 29.6 8.3a65.45 65.45 0 0 1 -29.2-54.6c0-12.2 3.2-23.4 8.9-33.1 32.3 39.8 80.8 65.8 135.2 68.6-9.3-44.5 24-80.6 64-80.6 18.9 0 35.9 7.9 47.9 20.7 14.8-2.8 29-8.3 41.6-15.8-4.9 15.2-15.2 28-28.8 36.1 13.2-1.4 26-5.1 37.8-10.2-8.9 13.1-20.1 24.7-32.9 34z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-809d6f81\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/www.linkedin.com\/shareArticle?url=\" tabindex=\"0\" role=\"button\" aria-label=\"linkedin\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n<\/div>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-0d44a065\" id=\"hochzeitsfotografie-Langwieder See\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-4d5691ef\"><h2 class=\"uagb-heading-text\">Einblicke in meine Hochzeitsreportagen | Hochzeitsfotograf Langwieder See<\/h2><p class=\"uagb-desc-text\">WHITE AND LIGHT PORTFOLIO<\/p><\/div>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-23db181a uagb-columns__columns-3 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-518ce70a\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-1a2fff83\"><div class=\"uagb-column__overlay\"><\/div>\n<p>Jede Hochzeit ist ein einzigartiges und unvergleichliches Ereignis. Sie widerspiegelt die Liebe, das Gl\u00fcck und die Emotionen des Brautpaares und ist gepr\u00e4gt von der Stimmung, dem Temperament und dem Charakter des Paares.<\/p>\n\n\n\n<p>Als <strong>Hochzeitsfotograf am Langwieder See<\/strong> ist es meine Aufgabe, die besonderen Momente der Hochzeitszeremonie im <strong>Standesamt<\/strong> und in der <strong>Kirche<\/strong> zu sch\u00e4tzen und deren emotionale Komplexit\u00e4t und auserlesene Atmosph\u00e4re diskret zu erfassen.<\/p>\n\n\n\n<p>Mit meiner Kamera halte ich die Zeremonie professionell, emotions- und wahrheitsgetreu fest. So entstehen absolut einzigartige <strong>Hochzeitsreportagen<\/strong> und <strong>Portraits<\/strong>, die Freude schenken und gl\u00fcckliche Ausrufe provozieren.<\/p>\n\n\n\n<p>Die Galerien in meinem Portfolio sind ein sprechender Beweis daf\u00fcr, dass jede Hochzeit ein Unikat ist.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-1448e84b\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n<\/div><\/section>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-right:0;margin-bottom:20px;margin-left:0;grid-template-columns:auto 60%\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ff8335b5\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-in-muenchen\/\">M\u00e4rchenhafte Hochzeit<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-in-muenchen\/\">Die Hochzeit von Anna und Veaceslav war ein wahr gewordener Traum. Umgeben von einer atemberaubenden Kulisse feierten sie ihre Liebe mit ihren engsten Familienmitgliedern und Freunden. Dabei entstanden unvergessliche Momente und Erinnerungen, die sie ein Leben lang begleiten werden.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-in-muenchen\/\"><img data-dominant-color=\"7d8a7e\" data-has-transparency=\"false\" style=\"--dominant-color: #7d8a7e;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_reportage-jpg.webp\" alt=\"Fotoreportage \u2013 Fotograf in Standesamt Langwieder See\" class=\"wp-image-11432 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-bottom:20px;padding-top:0px;padding-bottom:0px;grid-template-columns:60% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-bamberger-haus\/\"><img data-dominant-color=\"7a6764\" data-has-transparency=\"false\" style=\"--dominant-color: #7a6764;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_braut-jpg.webp\" alt=\"hochzeitsfotograf muenchen braut\" class=\"wp-image-11428 size-full not-transparent\"\/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-4b6b96b7\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-bamberger-haus\/\">Romantische Hochzeit<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-bamberger-haus\/\">Zwei junge Herzen, vereint in Liebe. Anna und Michael strahlen Z\u00e4rtlichkeit auf ihren Hochzeitsfotos. R\u00fchrende Trauung in der Dreieinigkeitskirche, bezauberndes Shooting im Hofgarten und gem\u00fctliche Feier in \u201eLa Villa im Bambergerhaus\u201c \u2013 ein perfekter Tag voller Gl\u00fcck.<\/a><\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-right:0;margin-bottom:20px;margin-left:0;grid-template-columns:auto 60%\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c54b98db\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsreportage-muenchen\/\">Hochzeit in goldenen Herbstt\u00f6nen<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsreportage-muenchen\/\">Kristina und Boris haben ihre Liebe mit einer bezaubernden Hochzeit an einem wundersch\u00f6nen Herbsttag zelebriert. Die bunte Pracht der Bl\u00e4tter schm\u00fcckte die Umgebung und verlieh der Hochzeit eine m\u00e4rchenhafte Atmosph\u00e4re.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsreportage-muenchen\/\"><img data-dominant-color=\"7f736f\" data-has-transparency=\"false\" style=\"--dominant-color: #7f736f;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_foto-1-jpg.webp\" alt=\"hochzeitsfotograf muenchen foto\" class=\"wp-image-11429 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-bottom:20px;padding-top:0px;padding-bottom:0px;grid-template-columns:60% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-fraueninsel\/\"><img data-dominant-color=\"84645c\" data-has-transparency=\"false\" style=\"--dominant-color: #84645c;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_-hochzeitsfotografie-jpg.webp\" alt=\"hochzeitsfotograf muenchen hochzeitsfotografie\" class=\"wp-image-11425 size-full not-transparent\"\/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-22dac786\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-fraueninsel\/\">Kirchliche Trauung<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-fraueninsel\/\">Maria und Florian gaben sich im antiken Ambiente das Ja-Wort. Mit prickelndem Getr\u00e4nk und fr\u00f6hlichem Jubel feierten die G\u00e4ste das frisch verm\u00e4hlte Paar. In gem\u00fctlicher Atmosph\u00e4re lie\u00dfen Maria und Florian ihren Hochzeitstag mit Familie und Freunden ausklingen.<\/a><\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-right:0;margin-bottom:20px;margin-left:0;grid-template-columns:auto 60%\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d8151400\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-gut-georgenberg-glonn\/\">Rustikales Ambiente f\u00fcr eine gem\u00fctliche Hochzeit<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-gut-georgenberg-glonn\/\">Von der idyllischen Gartenkirche bis zu den gem\u00fctlichen Speiser\u00e4umen strahlte die Nat\u00fcrlichkeit der Umgebung die Liebe und Z\u00e4rtlichkeit des Paares perfekt aus.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-gut-georgenberg-glonn\/\"><img data-dominant-color=\"878787\" data-has-transparency=\"false\" style=\"--dominant-color: #878787;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_-brautstrauss-jpg.webp\" alt=\"hochzeitsfotograf muenchen brautstrauss\" class=\"wp-image-11423 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-bottom:20px;padding-top:0px;padding-bottom:0px;grid-template-columns:60% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotografie-muenchen\/\"><img data-dominant-color=\"595c50\" data-has-transparency=\"false\" style=\"--dominant-color: #595c50;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_-kundenstimmen-jpg.webp\" alt=\"Mandlstra\u00dfe \u2013 Fotograf in Standesamt Langwieder See\" class=\"wp-image-11426 size-full not-transparent\"\/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-e11abd9d\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotografie-muenchen\/\">Ein erf\u00fclltes M\u00e4rchen<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotografie-muenchen\/\">Es gibt einen Moment im Leben, in dem M\u00e4rchentr\u00e4ume wahr werden. Es ist die Zeit der Liebe, wenn zwei Herzen sich finden und wissen, dass sie f\u00fcreinander bestimmt sind. Erleben Sie die romantische Hochzeit von Nancy und Udo \u2013 eine Geschichte, in der der Prinz seine Prinzessin gefunden hat.<\/a><\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-right:0;margin-bottom:20px;margin-left:0;grid-template-columns:auto 60%\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-00233554\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-thailand\/\">Hochzeit am Ozeanufer<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-thailand\/\">Die Jugend und Anmut des Brautpaares spiegelten sich in der lebhaften und emotionalen Atmosph\u00e4re des Fotoshootings wider. Gekr\u00f6nt wurde der Tag von einer traumhaften Trauung am Strand, malerisch eingebettet zwischen Himmel und Meer.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-thailand\/\"><img data-dominant-color=\"a48e7d\" data-has-transparency=\"false\" style=\"--dominant-color: #a48e7d;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_leistungen-jpg.webp\" alt=\"hochzeitsfotograf muenchen leistungen\" class=\"wp-image-11430 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-bottom:20px;padding-top:0px;padding-bottom:0px;grid-template-columns:60% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/standesamtliche-hochzeit-muenchen\/\"><img data-dominant-color=\"6c6f70\" data-has-transparency=\"false\" style=\"--dominant-color: #6c6f70;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/anna_roman_hochzeit_muenchen50-jpg.webp\" alt=\"Hochzeit \u2013 Fotograf in Standesamt Langwieder See\" class=\"wp-image-11422 size-full not-transparent\"\/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-02fd17f9\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-thailand\/\">Standesamtliche Hochzeit<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/standesamtliche-hochzeit-muenchen\/\">Anna und Roman, ein Paar das mit seiner Energie und Fr\u00f6hlichkeit alle um sich herum ansteckte. Ihre Hochzeit war ein Spiegelbild ihres Wesens: sonnig, herzlich und voller Lachen.<\/a><\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-right:0;margin-bottom:20px;margin-left:0;grid-template-columns:auto 60%\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ea2a6bdc\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/italienische-hochzeit\/\">Hochzeit im oberbayrischen Land<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/italienische-hochzeit\/\">Stephanie und Giuseppe haben sich das Ja-Wort gegeben und ihre Liebe ausgiebig gefeiert \u2013 ein Fest der Liebe und des Zusammenseins, ganz im Stil einer klassisch italienischen Familienfeier \u2013 stilvoll und elegant, voller Lebensfreude und ausgelassener Stimmung.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/italienische-hochzeit\/\"><img data-dominant-color=\"766d66\" data-has-transparency=\"false\" style=\"--dominant-color: #766d66;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_romantische_hochzeit-jpg.webp\" alt=\"hochzeitsfotograf muenchen romantische hochzeit\" class=\"wp-image-11433 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-bottom:20px;padding-top:0px;padding-bottom:0px;grid-template-columns:60% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-ostersee\/\"><img data-dominant-color=\"748174\" data-has-transparency=\"false\" style=\"--dominant-color: #748174;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_-preise-jpg.webp\" alt=\"hochzeitsfotograf muenchen preise\" class=\"wp-image-11427 size-full not-transparent\"\/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-34b95a6e\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-ostersee\/\">Zweimal das Jawort<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeit-ostersee\/\">Michaela und Severin entschieden sich, ihre Hochzeit in zwei verschiedenen Stilen zu feiern: standesamtlich und kirchlich, um traditionelle bayerische und europ\u00e4ische Elemente zu integrieren. Es war ein unvergessliches Fest voller Liebe, das sie mit Familie und Freunden teilten.<\/a><\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-right:0;margin-bottom:20px;margin-left:0;grid-template-columns:auto 60%\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-12c6710c\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-tegernsee\/\">Herzliche W\u00e4rme<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-tegernsee\/\">Die intime Hochzeit fand im Kreis der Familie statt. An der Seite des gl\u00fccklichen Paares strahlte ihr entz\u00fcckendes Baby, das die Zeremonie mit seinem fr\u00f6hlichen Lachen bereicherte. Das traditionelle chinesische zweite Hochzeitskleid der Braut verlieh der Hochzeit eine besondere Note.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-tegernsee\/\"><img data-dominant-color=\"6b6b6b\" data-has-transparency=\"false\" style=\"--dominant-color: #6b6b6b;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_-guenstig-jpg.webp\" alt=\"Hochzeitsfotografie \u2013 Fotograf in Standesamt Langwieder See\" class=\"wp-image-11424 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:20px;margin-bottom:20px;padding-top:0px;padding-bottom:0px;grid-template-columns:60% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-burghausen\/\"><img data-dominant-color=\"809593\" data-has-transparency=\"false\" style=\"--dominant-color: #809593;\" decoding=\"async\" width=\"700\" height=\"466\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen_location-jpg.webp\" alt=\"hochzeitsfotograf muenchen location\" class=\"wp-image-11431 size-full not-transparent\"\/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c173d735\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-burghausen\/\">Wer sagt, dass eine Braut in Wei\u00df heiraten muss?<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-burghausen\/\">Warum sollte eine Braut sich nur in Wei\u00df kleiden? Alte und neue Traditionen k\u00f6nnen auf einer Hochzeit miteinander vereint werden. Ein bezauberndes Hochzeitspaar, traditionell gekleidet, strahlte Harmonie in den alten Gem\u00e4uern des Rathauses aus. <\/a><\/p><\/div>\n<\/div><\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-8d2c8d2f\" id=\"hochzeitsfotograf-standesamt-Langwieder See\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ba89df19\"><h2 class=\"uagb-heading-text\">Hochzeitspaket<br>Hochzeitsfotograf Langwieder See<\/h2><p class=\"uagb-desc-text\">JEDES HOCHZEITSPAKET UMFASST FOLGENDE LEISTUNGEN<\/p><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-83ef8e01 wp-block-columns-is-layout-flex\" style=\"margin-bottom:25px\">\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-4925a6cfb793b02d50902bd4c10791c8 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"single\">Beratung<\/h3>\n\n\n\n<p class=\"has-normal-font-size\" style=\"line-height:1.5\">Gerne bespreche ich mit Ihnen in einem WhatsApp-Videoanruf oder pers\u00f6nlich in meinem B\u00fcro alle Details Ihrer Hochzeit.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-c71e324a921339be9a1c9e299682b483 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"family\">Paarshooting<\/h3>\n\n\n\n<p class=\"has-normal-font-size\" style=\"line-height:1.5\">Die Fotoreportage h\u00e4lt die wichtigsten Momente eurer Hochzeit fest, w\u00e4hrend das Paarshooting emotionale und romantische Bilder von euch beiden einf\u00e4ngt.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-6139e0224a60c81bc30bf07e729f4f3d is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"patron\">80 Fotos<\/h3>\n\n\n\n<p class=\"has-normal-font-size\" style=\"line-height:1.5\">Im Durchschnitt erhalten Sie pro Stunde Fotoreportage 80 Fotos. So k\u00f6nnen Sie sicher sein, dass alle wichtigen Momente Ihres gro\u00dfen Tages festgehalten werden.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-83ef8e01 wp-block-columns-is-layout-flex\" style=\"margin-bottom:25px\">\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-529b8ef5ef6a441837510db51ed57e72 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"single\">Nachbearbeitung<\/h3>\n\n\n\n<p class=\"has-normal-font-size\" style=\"line-height:1.5\">Alle Fotos werden in naturgetreuen Farben bearbeitet. Auf Wunsch erhalten Sie zus\u00e4tzlich alle Fotos im beliebten Moody Boho Look.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-3131c1f3b2236ded18d0a805d4dc8378 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"family\">Fotos auf USB<\/h3>\n\n\n\n<p class=\"has-normal-font-size\" style=\"line-height:1.5\">Alle Fotos des Hochzeitstags erhalten Sie in exzellenter Qualit\u00e4t auf einem USB-Stick, damit Sie alle Momente in bester Aufl\u00f6sung f\u00fcr die Ewigkeit festhalten k\u00f6nnen.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-6fa1cd1356b8d0e7619ccb3cff2122aa is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"patron\">40 Fotoabz\u00fcge<\/h3>\n\n\n\n<p class=\"has-normal-font-size\" style=\"line-height:1.5\">Sie erhalten 40 von mir ausgew\u00e4hlte professionelle Fotoabz\u00fcge im Format 13 x 19 cm auf hochwertigem Archivpapier.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-83ef8e01 wp-block-columns-is-layout-flex\" style=\"margin-bottom:25px\">\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-03d258e567c94caefcc66a303a49f3f4 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"single\">Online-Galerie<\/h3>\n\n\n\n<p class=\"has-normal-font-size\" style=\"line-height:1.5\">Teilen Sie Ihre Freude mit Familie und Freunden! In einer Online-Galerie k\u00f6nnen Sie Ihre Fotos ansehen und kostenlos herunterladen.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-acd98e32078962434425002af3e2aaf5 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"family\">Fotos in 2 Wochen<\/h3>\n\n\n\n<p class=\"has-normal-font-size\" style=\"line-height:1.5\">Die Fotos stehen Ihnen innerhalb von 2 Wochen nach dem Hochzeitstag zur Verf\u00fcgung. Ich werde Sie per E-Mail sofort benachrichtigen, sobald die Fotos bereit sind.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-f3d24e36fd5a96bc52cc2e610d8a123b is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"patron\">Nutzungsrechte<\/h3>\n\n\n\n<p>Alle Nutzungsrechte an den Fotos liegen bei Ihnen. Vertraglich \u00fcbertrage ich Ihnen die Nutzungsrechte, so dass Sie die Fotos frei verwenden und teilen k\u00f6nnen.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-83ef8e01 wp-block-columns-is-layout-flex\" style=\"margin-bottom:25px\">\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-55277fbf9eda0692e635a1697f10d31d is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"single\">Flexible Begleitung<\/h3>\n\n\n\n<p class=\"has-normal-font-size\" style=\"line-height:1.5\">Sollten Sie w\u00e4hrend der Feier feststellen, dass Sie mich doch noch etwas l\u00e4nger ben\u00f6tigen, ist dies nat\u00fcrlich kein Problem.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-b5fb71d3a01afdf58e3ac27c430f6d2e is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#f4f0ed;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading\" id=\"family\">Reisekosten inklusive<\/h3>\n\n\n\n<p class=\"has-normal-font-size\" style=\"line-height:1.5\">F\u00fcr Hochzeiten im Umkreis von 100 km um M\u00fcnchen entfallen s\u00e4mtliche Anfahrtskosten.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-aac492badc606e718048bb61df908589 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#706b66;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h3 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-af41b77d2de5168db89b2883a8f31d17\" id=\"patron\">Keine Vorauszahlung<\/h3>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color has-normal-font-size wp-elements-628bd66ff40668f6a52fa63a54972f82\" style=\"line-height:1.5\">Die Bezahlung erfolgt erst nach der Hochzeit, es ist keine Vorauszahlung erforderlich.<\/p>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-89070a25\" id=\"hochzeitsfotograf-standesamt-Langwieder See\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-702b6753\"><h2 class=\"uagb-heading-text\">Ein Blick hinter die Kulissen von W&amp;L \u2013 Hochzeitsfotograf Langwieder See <\/h2><p class=\"uagb-desc-text\">WHITE AND LIGHT BLOG<\/p><\/div>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-2d8fb6c8 uagb-columns__columns-3 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-b78e985d\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-9bbc0ec6\"><div class=\"uagb-column__overlay\"><\/div>\n<p>Werfen Sie einen Blick hinter die Kulissen und entdecken Sie meinen Blog! Hier \u00f6ffne ich T\u00fcrchen f\u00fcr all jene, die mehr \u00fcber meine Arbeit und meine Leidenschaft f\u00fcr die Fotografie erfahren m\u00f6chten.<\/p>\n\n\n\n<p>Mit Freude teile ich meine Erfahrungen und Erlebnisse rund um Hochzeiten, Paarshootings und andere Events. Tauchen Sie ein in die Welt der Hochzeitsfotografie und lassen Sie sich von meinen Bildern und Geschichten inspirieren.<\/p>\n\n\n\n<p>Ich freue mich, wenn Sie meine Blogbeitr\u00e4ge interessant finden und hoffe, dass Sie hier viele n\u00fctzliche Tipps und Tricks rund um das Thema Fotografie finden k\u00f6nnen.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-b2add8f1\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n<\/div><\/section>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-6895325c\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/10k-followers-instagram\/\">10K Followers auf Instagram<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/10k-followers-instagram\/\">Mit Stolz und Dankbarkeit blicke ich auf diesen Meilenstein, den wir gemeinsam erreicht haben. An alle meine Follower aus nah und fern: Danke, dass ihr Teil dieser Reise seid!<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/10k-followers-instagram\/\"><img data-dominant-color=\"2c2021\" data-has-transparency=\"false\" style=\"--dominant-color: #2c2021;\" decoding=\"async\" width=\"700\" height=\"379\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/10k_instagram-hochzeitsfotograf-muenchen-p-1-jpg.webp\" alt=\"10k instagram hochzeitsfotograf muenchen\" class=\"wp-image-11454 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0bf0d4a8\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/brautstrauss-muenchen\/\">Brautstrau\u00df \u2013 Spiegelbild der Braut<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/brautstrauss-muenchen\/\">Mehr als ein Accessoire, spiegelt der Strau\u00df die Seele der Braut wider und f\u00fcgt der <strong>Hochzeit<\/strong> eine tiefgr\u00fcndige Note hinzu.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/brautstrauss-muenchen\/\"><img data-dominant-color=\"2e2b1b\" data-has-transparency=\"false\" style=\"--dominant-color: #2e2b1b;\" decoding=\"async\" width=\"700\" height=\"379\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/brautstrause-und-ansteckblumen-galerie-fur-ihre-inspiration-p-1-jpg.webp\" alt=\"brautstrause und ansteckblumen galerie fur ihre inspiration\" class=\"wp-image-11455 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30);padding-top:0;padding-bottom:0\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-cac5f992\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/kamera-kaufberatung\/\">Kamera Kaufberatung<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/kamera-kaufberatung\/\">Profitieren Sie von Erfahrungsberichten und konkreten Empfehlungen f\u00fcr optimale Ergebnisse bei <strong>Hochzeitsfotos<\/strong>.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/kamera-kaufberatung\/\"><img data-dominant-color=\"574b46\" data-has-transparency=\"false\" style=\"--dominant-color: #574b46;\" decoding=\"async\" width=\"700\" height=\"379\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/kamerakaufberatung-p-1-jpg.webp\" alt=\"kamerakaufberatung\" class=\"wp-image-11459 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ee7f1338\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsdekoration-muenchen\/\">Liebe zum Detail<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsdekoration-muenchen\/\">Sorgf\u00e4ltig ausgew\u00e4hlte Dekoration und Blumenarrangements schaffen die perfekte Atmosph\u00e4re f\u00fcr Ihre <strong>Traumhochzeit<\/strong>. Ob elegant, luxuri\u00f6s, frisch oder verspielt \u2013 setzen Sie auf Details, die Ihre Individualit\u00e4t unterstreichen.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsdekoration-muenchen\/\"><img data-dominant-color=\"665e5e\" data-has-transparency=\"false\" style=\"--dominant-color: #665e5e;\" decoding=\"async\" width=\"700\" height=\"379\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeits-und-eventdekoration-in-munchen_p-1-jpg.webp\" alt=\"hochzeits und eventdekoration in munchen\" class=\"wp-image-11458 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-4d2a3361\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-guru\/\">Preisgekr\u00f6ntes Foto<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-guru\/\">In der Kategorie \u201eTop Pick\u201c des <strong>Hochzeitswettbewerbs<\/strong> auf GuruShots gewann das Foto den Titel \u201eGuru\u201c. Die Jugend und Z\u00e4rtlichkeit des Brautpaares inspirierte mich zu diesem liebevollen Bild.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf-guru\/\"><img data-dominant-color=\"736c69\" data-has-transparency=\"false\" style=\"--dominant-color: #736c69;\" decoding=\"async\" width=\"700\" height=\"379\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/gurus_top_pick_winner_p-1-jpg.webp\" alt=\"gurus top pick winner\" class=\"wp-image-11457 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-73311da9\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/trauringe-muenchen\/\">Symbol der ewigen Liebe<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/trauringe-muenchen\/\">Ein Trauring ist weit mehr als ein edles Accessoire. Er ist ein st\u00e4ndiger Begleiter, der eine tiefe Bedeutung tr\u00e4gt. Er symbolisiert das Ja-Wort und das unendliche Liebesversprechen an den Partner.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/trauringe-muenchen\/\"><img data-dominant-color=\"967367\" data-has-transparency=\"false\" style=\"--dominant-color: #967367;\" decoding=\"async\" width=\"700\" height=\"379\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/trauringe-galerie-fur-ihre-inspiration_p-1-jpg.webp\" alt=\"trauringe galerie fur ihre inspiration\" class=\"wp-image-11461 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f5012ece\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotografie-mit-der-canon\/\">Checkliste f\u00fcr Portr\u00e4taufnahmen<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotografie-mit-der-canon\/\">Canon w\u00e4hlte eines meiner <strong>Hochzeitsportraits<\/strong> f\u00fcr den Artikel &#8222;Kurze Checkliste f\u00fcr Portr\u00e4taufnahmen&#8220; auf ihrer Lernplattform. Der Artikel bietet wertvolle Tipps f\u00fcr Profis und Neulinge.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeitsfotografie-mit-der-canon\/\"><img data-dominant-color=\"b6b0b3\" data-has-transparency=\"false\" style=\"--dominant-color: #b6b0b3;\" decoding=\"async\" width=\"700\" height=\"379\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/Canon-Quick-portrait-checklist-p-1-jpg.webp\" alt=\"Canon Quick portrait checklist\" class=\"wp-image-11456 size-full not-transparent\"\/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"margin-top:var(--wp--preset--spacing--30);margin-bottom:var(--wp--preset--spacing--30)\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-de14c2cf\"><h3 class=\"uagb-heading-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeits-dj-in-muenchen\/\">Tipp f\u00fcr die Hochzeitsplanung<\/a><\/h3><p class=\"uagb-desc-text\"><a href=\"https:\/\/whiteandlight.com\/hochzeits-dj-in-muenchen\/\"><strong>Hochzeitsvorbereitungen<\/strong> gleichen einem Puzzle. Viele Teile ergeben ein Bild \u2013 den unvergesslichen<strong> Hochzeitstag<\/strong>. Datum, Ort, G\u00e4ste, Trauung, Catering, Musik, Fotografie, Dekoration \u2013 alles muss passen.<\/a><\/p><\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/whiteandlight.com\/hochzeits-dj-in-muenchen\/\"><img data-dominant-color=\"7f7574\" data-has-transparency=\"false\" style=\"--dominant-color: #7f7574;\" decoding=\"async\" width=\"700\" height=\"379\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/tipps_fuer_die_-hochzeitsplanung-fixando_p-1-jpg.webp\" alt=\"tipps fuer die hochzeitsplanung fixando\" class=\"wp-image-11460 size-full not-transparent\"\/><\/a><\/figure><\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-3dcbfd0b\" id=\"hochzeitsfotografie-Langwieder See\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b1c1270e\"><h2 class=\"uagb-heading-text\">Hochzeitspaare \u00fcber W&amp;L &#8211; Hochzeitsfotograf Langwieder See<\/h2><p class=\"uagb-desc-text\">KUNDENSTIMMEN<\/p><\/div>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-277b889b uagb-columns__columns-3 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-78bffa72\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-17a51565\"><div class=\"uagb-column__overlay\"><\/div>\n<p>Die Zufriedenheit meiner Kunden liegt mir am Herzen. Ihre Meinung ist mir daher sehr wichtig und hilft mir, meine Arbeit stetig zu verbessern und an den Bed\u00fcrfnissen meiner Kunden am Langwieder See und Umgebung auszurichten.<br><br>Aus diesem Grund lade ich Sie herzlich ein, die Erfahrungsberichte anderer Kunden auf meiner Website zu lesen. Diese ehrlichen Bewertungen geben Ihnen einen unverf\u00e4lschten Einblick in die Qualit\u00e4t meiner Dienstleistungen und die Zufriedenheit meiner Kunden.<br><br>Sie haben bereits einen Fotoauftrag bei White and Light \u2013 Hochzeitsfotograf am Langwieder See gebucht? Dann w\u00fcrde ich mich sehr freuen, wenn Sie mir Ihre Meinung auf der Google Maps-Seite von White and Light hinterlassen w\u00fcrden. Ihre Bewertung hilft mir, meine Arbeit weiterzuentwickeln und anderen Kunden am Langwieder See bei der Suche nach einem passenden Fotografen zu unterst\u00fctzen. Vielen Dank f\u00fcr Ihr Vertrauen!<\/p>\n\n\n\n<div class=\"wp-block-uagb-team uagb-team__image-position-above uagb-team__align-center uagb-team__stack-tablet uagb-block-c4de3121\"><div class=\"uagb-team__content\"><img decoding=\"async\" class=\"uagb-team__image-crop-circle\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/Bewertung_hochzeitsfotograf-jpg.webp\" alt=\"Bewertung Hochzeitsfotograf\" height=\"320\" width=\"320\" loading=\"lazy\"\/><h3 class=\"uagb-team__title\">Julia &amp; Michael<\/h3><span class=\"uagb-team__prefix\"><\/span><p class=\"uagb-team__desc\"><\/p><\/div><\/div>\n\n\n\n<p>Andrej Nikolajew hat vor kurzem unsere kleine Hochzeitsfeier mit einer Fotoreportage begleitet. F\u00fcr uns war besonders wichtig an dem Tag einen echten Profi mit Herz zu haben, bei dem man auch menschlich gut aufgehoben f\u00fchlt. Mit Andrej haben wir f\u00fcr unseren Hochzeitstag eine wirklich sehr gute Wahl getroffen! Das wichtigste: Die Fotos sind lebendig, emotional, mit Liebe und einfach sch\u00f6n!<\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-color has-text-color has-link-color has-medium-font-size wp-elements-ec6f11c5559b38b283400a0dab1f6e19\">\u2605\u2605\u2605\u2605\u2605<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-473a530a\"><h3 class=\"uagb-heading-text\">Bester Hochzeitsfotograf<\/h3><\/div>\n\n\n\n<p>Bester Hochzeitsfotograf EVER! Andrej hat uns sowohl bei unserer standesamtlichen als auch bei unserer kirchlichen Trauung begleitet und die Fotos sind wundersch\u00f6n geworden! Ich kann ihn nur w\u00e4rmstens empfehlen!<br><em>Corinna und Jonathan<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-color has-text-color has-link-color has-medium-font-size wp-elements-ec6f11c5559b38b283400a0dab1f6e19\">\u2605\u2605\u2605\u2605\u2605<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-77f44068\"><h3 class=\"uagb-heading-text\">Bilder sind sensationell<\/h3><\/div>\n\n\n\n<p>Andrej ist ein hervorragender Fotograf, der unsere Hochzeit stets zur\u00fcckhaltend und mit viel Humor begleitet hat. Seine Bilder sind sensationell. Eine absolute Empfehlung!<br><em>Rebecca und Tobias<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-color has-text-color has-link-color has-medium-font-size wp-elements-ec6f11c5559b38b283400a0dab1f6e19\">\u2605\u2605\u2605\u2605\u2605<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-980dae1a\"><h3 class=\"uagb-heading-text\">Hoch professionelle Kommunikation<\/h3><\/div>\n\n\n\n<p>Andrej k\u00f6nnen wir w\u00e4rmstens als Hochzeitsfotograf empfehlen. Hoch professionelle Kommunikation, Vorbereitung und Durchf\u00fchrung! Die Fotos sind wundersch\u00f6n geworden und bilden die perfekte Erinnerung an einen unvergesslichen Tag.<br><em>Tina und Guillermo <\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-color has-text-color has-link-color has-medium-font-size wp-elements-ec6f11c5559b38b283400a0dab1f6e19\">\u2605\u2605\u2605\u2605\u2605<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b90c3bdc\"><h3 class=\"uagb-heading-text\">Andrej bringt viel gute Laune und positive Energie mit<\/h3><\/div>\n\n\n\n<p>Andrej hat unsere standesamtliche Hochzeitsfeier vier Stunden lang fotografisch begleitet und wir sind sehr gl\u00fccklich \u00fcber die sch\u00f6nen Bildern, die er von uns und unseren G\u00e4sten gemacht hat. Andrej ist zuverl\u00e4ssig, offen und bringt viel gute Laune und positive Energie mit. Seine Resultate hat er schnell mit uns geteilt. Wir k\u00f6nnen ihn nur weiterempfehlen! Danke f\u00fcr alles!<br><em>Caroline und Ignatius<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-color has-text-color has-link-color has-medium-font-size wp-elements-ec6f11c5559b38b283400a0dab1f6e19\">\u2605\u2605\u2605\u2605\u2605<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0b9299ec\"><h3 class=\"uagb-heading-text\">Supersch\u00f6ne und nat\u00fcrliche Fotos<\/h3><\/div>\n\n\n\n<p>Durchweg supersch\u00f6ne und nat\u00fcrliche Fotos! Wir und unsere G\u00e4ste sind von den erhaltenen Bildern und der zur\u00fcckhaltenden, sehr freundlichen und professionellen Art des Fotografen begeistert! Eine klare Empfehlung! Wir lieben die Bilder!<br><em>Sandra und Hans<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-color has-text-color has-link-color has-medium-font-size wp-elements-ec6f11c5559b38b283400a0dab1f6e19\">\u2605\u2605\u2605\u2605\u2605<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c5730d29\"><h3 class=\"uagb-heading-text\">Wir w\u00fcrden Andrej jederzeit weiterempfehlen<\/h3><\/div>\n\n\n\n<p>Wir haben Andrej als unseren Hochzeitsfotografen gebucht. Wir waren sehr zufrieden. Die Bilder sind wundersch\u00f6n geworden. Seine Ideen waren frisch und unaufdringlich. Bei der Feier war er kaum wahrzunehmen und hat tolle authentische Momente aufgenommen. Wir w\u00fcrden ihn jederzeit weiterempfehlen.<br><em>Annabell und Michael<\/em><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-ec1328dc\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-color uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-6b718ec7 uagb-columns__columns-1 uagb-columns__max_width-theme uagb-columns__valign-undefined alignundefined\" id=\"hochzeitsfotograf-Langwieder See-empfehlung\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-706e2ead\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-advanced-heading uagb-block-08efe18e\"><h3 class=\"uagb-heading-text\">Sie inspirieren mich!<\/h3><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u25b6\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/tidiBU7Dwu4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-8bbe97ca\" id=\"hochzeitsfotograf-standesamt-Langwieder See\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c1333379\"><h2 class=\"uagb-heading-text\">Von der Buchung bis zur Bild\u00fcbergabe: Hochzeitsfotograf Langwieder See \u2013 So einfach ist es!<\/h2><p class=\"uagb-desc-text\">ABLAUF<\/p><\/div>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-7a32fb13 uagb-columns__columns-3 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-367a9019\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-ac384ca8\"><div class=\"uagb-column__overlay\"><\/div>\n<p>Ich freue mich, dass Sie Es freut mich, dass Sie mich als Ihren Hochzeitsfotografen in Betracht ziehen. Hier ist eine verk\u00fcrzte Darstellung unseres gemeinsamen Weges von der ersten Kontaktaufnahme bis zur \u00dcbergabe der Bilder nachdenken, mich als Hochzeitsfotograf f\u00fcr Ihren besonderen Tag zu engagieren. Im Folgenden m\u00f6chte ich Ihnen den Ablauf unserer Zusammenarbeit von der Buchung bis hin zur Bild\u00fcbergabe erl\u00e4utern.<\/p>\n\n\n\n<div class=\"schema-how-to wp-block-yoast-how-to-block\"><p class=\"schema-how-to-description\">DIE WICHTIGSTEN PUNKTE IM \u00dcBERBLICK<\/p> <ol class=\"schema-how-to-steps\"><li class=\"schema-how-to-step\" id=\"how-to-step-1711372022508\"><strong class=\"schema-how-to-step-name\">Anfrage<\/strong> <p class=\"schema-how-to-step-text\">Nehmen Sie Kontakt mit mir auf \u2013 entweder \u00fcber meine Website oder per E-Mail. Teilen Sie mir Ihr Hochzeitsdatum und den Veranstaltungsort mit.<\/p> <\/li><li class=\"schema-how-to-step\" id=\"how-to-step-1711372061753\"><strong class=\"schema-how-to-step-name\">Angebot<\/strong> <p class=\"schema-how-to-step-text\">Ich erstelle ein individuelles Angebot und sende es Ihnen zu.<\/p> <\/li><li class=\"schema-how-to-step\" id=\"how-to-step-1711372167394\"><strong class=\"schema-how-to-step-name\">Kennenlernengespr\u00e4ch<\/strong> <p class=\"schema-how-to-step-text\">In einem pers\u00f6nlichen Gespr\u00e4ch per WhatsApp-Videoanruf oder in meinem B\u00fcro besprechen wir Ihre W\u00fcnsche und Vorstellungen f\u00fcr die fotografische Begleitung.<\/p> <\/li><li class=\"schema-how-to-step\" id=\"how-to-step-1711372187195\"><strong class=\"schema-how-to-step-name\">Buchung<\/strong> <p class=\"schema-how-to-step-text\">Sobald wir alle Details besprochen haben, erhalten Sie von mir einen Vertrag. Nach schriftlicher Zustimmung zum Vertrag bin ich f\u00fcr Sie gebucht.<\/p> <\/li><li class=\"schema-how-to-step\" id=\"how-to-step-1711372209273\"><strong class=\"schema-how-to-step-name\">Hochzeitstag<\/strong> <p class=\"schema-how-to-step-text\">Am Hochzeitstag bin ich p\u00fcnktlich vor Ort und werde jeden besonderen Moment in einzigartigen Bildern festhalten. Dabei arbeite ich dezent und professionell, um den Ablauf Ihrer Feier so wenig wie m\u00f6glich zu st\u00f6ren.<\/p> <\/li><li class=\"schema-how-to-step\" id=\"how-to-step-1711372222021\"><strong class=\"schema-how-to-step-name\">Bildbearbeitung<\/strong> <p class=\"schema-how-to-step-text\">Nach der Hochzeit bearbeite ich die Fotos sorgf\u00e4ltig, so erhalten Sie von mir hochwertige Bilder, die Ihre Hochzeit in bester Erinnerung behalten werden.<\/p> <\/li><li class=\"schema-how-to-step\" id=\"how-to-step-1711372240103\"><strong class=\"schema-how-to-step-name\">Bild\u00fcbergabe<\/strong> <p class=\"schema-how-to-step-text\">Die fertigen Fotos erhalten Sie in hoher Aufl\u00f6sung auf einem USB-Stick \u2013 sowohl in Farbe als auch in Schwarz-Wei\u00df und 40 von mir ausgew\u00e4hlte, ausbelichtete Fotoabz\u00fcge. Dar\u00fcber hinaus stelle ich Ihnen eine Online-Galerie zur Verf\u00fcgung, von der Ihre Familie und Freunde die Bilder bequem herunterladen k\u00f6nnen.<\/p> <\/li><li class=\"schema-how-to-step\" id=\"how-to-step-1711372251700\"><strong class=\"schema-how-to-step-name\">Bezahlung<\/strong> <p class=\"schema-how-to-step-text\">Die Rechnung erhalten Sie zusammen mit den Fotos. Der Betrag wird nach Erhalt der Rechnung f\u00e4llig.<\/p> <\/li><li class=\"schema-how-to-step\" id=\"how-to-step-1711390196442\"><strong class=\"schema-how-to-step-name\"><br\/>Feedback<\/strong> <p class=\"schema-how-to-step-text\">Ihre Zufriedenheit ist mir sehr wichtig. Wenn Sie mit meiner Arbeit als Hochzeitsfotograf zufrieden waren, w\u00fcrde ich mich \u00fcber Ihr Feedback und eine Bewertung auf Google Maps freuen.<\/p> <\/li><\/ol><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-67b1d583\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-gradient uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-9be43c1a uagb-columns__columns-4 uagb-columns__max_width-theme uagb-columns__valign-undefined alignundefined\" id=\"hochzeitsfotograf-Langwieder See-empfehlung\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-4\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-b89ae1af\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-advanced-heading uagb-block-338c35ad\"><h3 class=\"uagb-heading-text\">15<\/h3><p class=\"uagb-desc-text\">JAHRE<br>HOCHZEITSERFAHRUNG<\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-dbc69a40\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-advanced-heading uagb-block-87dd7e43\" id=\"fotografierte-hochzeiten\"><h3 class=\"uagb-heading-text\">500<\/h3><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-ff763022\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-advanced-heading uagb-block-358f8e56\"><h3 class=\"uagb-heading-text\">198<\/h3><p class=\"uagb-desc-text\">GESTALTETE<br>HOCHZEITSFOTOB\u00dcCHER<\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-4df8a0f6\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-advanced-heading uagb-block-38d32911\"><h3 class=\"uagb-heading-text\">21.600<\/h3><p class=\"uagb-desc-text\">AUSBELICHTETE<br>FOTOABZ\u00dcGE<\/p><\/div>\n<\/div>\n<\/div><\/section>\n<\/div>\n<\/div>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-f52ed514\" id=\"hochzeitsfotograf-Langwieder See-gesucht\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d408a4cd\"><h2 class=\"uagb-heading-text\">Suchen Sie einen Fotografen am Langwieder See?<\/h2><p class=\"uagb-desc-text\">RUFEN SIE MICH AN, SCHREIBEN SIE MIR EINE E-MAIL ODER NUTZEN SIE DAS KONTAKTFORMULAR<\/p><\/div>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-7525049a uagb-columns__columns-3 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-d2383292\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-17d1ba5d\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-team uagb-team__image-position-above uagb-team__align-center uagb-team__stack-tablet uagb-block-88e9eeaf uagb-team uagb-team__outer-wrap\"><div class=\"uagb-team__content\"><img decoding=\"async\" class=\"uagb-team__image-crop-circle\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/andrey_nikolaev_hochzeitsfotograf_muenchen-13.jpg\" alt=\"Andrej Nikolajew \u2013 Hochzeitsfotograf Langwieder See\" height=\"320\" width=\"320\" loading=\"lazy\"\/><h3 class=\"uagb-team__title\">Andrej Nikolajew<\/h3><span class=\"uagb-team__prefix\"><em>Ausgebildeter Fotograf und Dipl. Grafik-Designer<\/em><\/span><p class=\"uagb-team__desc\"><\/p><ul class=\"uagb-team__social-list\"><li class=\"uagb-team__social-icon\"><a href=\"https:\/\/g.page\/muenchenhochzeitsfotograf\/review?nr\" aria-label=\"google\" target=\"_blank\" title=\"\" rel=\"noopener noreferrer\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 488 512\"><path d=\"M488 261.8C488 403.3 391.1 504 248 504 110.8 504 0 393.2 0 256S110.8 8 248 8c66.8 0 123 24.5 166.3 64.9l-67.5 64.9C258.5 52.6 94.3 116.6 94.3 256c0 86.5 69.1 156.6 153.7 156.6 98.2 0 135-70.4 140.8-106.9H248v-85.3h236.1c2.3 12.7 3.9 24.9 3.9 41.4z\"><\/path><\/svg><\/a><\/li><li class=\"uagb-team__social-icon\"><a href=\"https:\/\/www.facebook.com\/WhiteAndLightHochzeitsfotografMuenchen\/\" aria-label=\"facebook-f\" target=\"_blank\" title=\"\" rel=\"noopener noreferrer\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 320 512\"><path d=\"M279.1 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.4 0 225.4 0c-73.22 0-121.1 44.38-121.1 124.7v70.62H22.89V288h81.39v224h100.2V288z\"><\/path><\/svg><\/a><\/li><li class=\"uagb-team__social-icon\"><a href=\"https:\/\/www.instagram.com\/whiteandlightphoto\/\" aria-label=\"instagram\" target=\"_blank\" title=\"\" rel=\"noopener noreferrer\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg><\/a><\/li><li class=\"uagb-team__social-icon\"><a href=\"https:\/\/gurushots.com\/andreynikolaev\/photos\" aria-label=\"camera\" target=\"_blank\" title=\"\" rel=\"noopener noreferrer\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M194.6 32H317.4C338.1 32 356.4 45.22 362.9 64.82L373.3 96H448C483.3 96 512 124.7 512 160V416C512 451.3 483.3 480 448 480H64C28.65 480 0 451.3 0 416V160C0 124.7 28.65 96 64 96H138.7L149.1 64.82C155.6 45.22 173.9 32 194.6 32H194.6zM256 384C309 384 352 341 352 288C352 234.1 309 192 256 192C202.1 192 160 234.1 160 288C160 341 202.1 384 256 384z\"><\/path><\/svg><\/a><\/li><\/ul><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-97be4caf\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-01d20fa3 uagb-columns__columns-3 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-color uagb-block-600787d0\"><div class=\"uagb-column__overlay\"><\/div>\n<p class=\"has-text-align-center\">Handy&nbsp;\u00b7&nbsp;WhatsApp<br>+49 176 66871288<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-4320229e\"><div class=\"uagb-column__overlay\"><\/div>\n<p class=\"has-text-align-center\">Festnetztelefon<br>+49 89 57087183<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-9634b985\"><div class=\"uagb-column__overlay\"><\/div>\n<p class=\"has-text-align-center\">E-Mail<em><br><\/em><a href=\"mailto:info@whiteandlight.com\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">info@whiteandlight.com<\/a><\/p>\n<\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-7ce3ba41\" id=\"bester-hochzeitsfotograf\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-c27f6d48 uagb-columns__columns-3 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-418941cd\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-f7e554f0\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c4cd187e\"><h2 class=\"uagb-heading-text\">Kontaktformular<\/h2><p class=\"uagb-desc-text\">Um Ihnen ein individuelles Angebot zu erstellen, ben\u00f6tige ich einige Informationen von Ihnen. Bitte f\u00fcllen Sie das folgende Kontaktformular aus und ich werde mich bei Ihnen umgehend melden:<\/p><\/div>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f12910-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"12910\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/hochzeitsfotograf\/wp-json\/wp\/v2\/pages\/12385#wpcf7-f12910-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"12910\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE_formal\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f12910-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-912\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Vorname der Braut\" value=\"\" type=\"text\" name=\"text-912\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-448\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Vorname des Br\u00e4utigams\" value=\"\" type=\"text\" name=\"text-448\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-Mail-Adresse\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-703\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Hochzeitsdatum\" value=\"\" type=\"text\" name=\"text-703\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-347\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Hochzeitsort\" value=\"\" type=\"text\" name=\"text-347\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-459\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"menu-459\"><option value=\"Dauer der Fotobegleitung\">Dauer der Fotobegleitung<\/option><option value=\"Ich wei\u00df noch nicht\">Ich wei\u00df noch nicht<\/option><option value=\"1 Stunde Fotoreportage\">1 Stunde Fotoreportage<\/option><option value=\"2 Stunden Fotoreportage\">2 Stunden Fotoreportage<\/option><option value=\"3 Stunden Fotoreportage\">3 Stunden Fotoreportage<\/option><option value=\"4 Stunden Fotoreportage\">4 Stunden Fotoreportage<\/option><option value=\"5 Stunden Fotoreportage\">5 Stunden Fotoreportage<\/option><option value=\"6 Stunden Fotoreportage\">6 Stunden Fotoreportage<\/option><option value=\"7 Stunden Fotoreportage\">7 Stunden Fotoreportage<\/option><option value=\"8 Stunden Fotoreportage\">8 Stunden Fotoreportage<\/option><option value=\"9 Stunden Fotoreportage\">9 Stunden Fotoreportage<\/option><option value=\"10 Stunden Fotoreportage\">10 Stunden Fotoreportage<\/option><option value=\"11 Stunden Fotoreportage\">11 Stunden Fotoreportage<\/option><option value=\"ab 12 Stunden Fotoreportage -200 \u20ac Rabatt\">ab 12 Stunden Fotoreportage -200 \u20ac Rabatt<\/option><\/select><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-832\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"menu-832\"><option value=\"Wie haben Sie mich gefunden?\">Wie haben Sie mich gefunden?<\/option><option value=\"Hochzeitsmagazin\">Hochzeitsmagazin<\/option><option value=\"Hochzeitsmesse\">Hochzeitsmesse<\/option><option value=\"Suchmaschine\">Suchmaschine<\/option><option value=\"Facebook\">Facebook<\/option><option value=\"Instagram\">Instagram<\/option><option value=\"Partnerseite\">Partnerseite<\/option><option value=\"Mundpropaganda\">Mundpropaganda<\/option><\/select><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-170\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"textarea-170\">Wir sind auf der Suche nach einem Hochzeitsfotografen, der unseren besonderen Tag in wundersch\u00f6nen Bildern festh\u00e4lt. Sollten Sie an diesem Tag verf\u00fcgbar sein, bitten wir Sie, uns Ihre Preise und Leistungen f\u00fcr eine Hochzeitsreportage zuzusenden. Wir freuen uns sehr auf Ihre Antwort!<\/textarea><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"quiz-526\"><label><span class=\"wpcf7-quiz-label\">Spamschutz: Wieviel ist 2 mal 2 =<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"quiz-526\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_quiz-526\" value=\"b1a41f0d77089e9365f80bfb36115d36\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Anfrage senden\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"96\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-2456f35d\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-a2a9fde4\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-call-to-action uagb-block-8e8e514c wp-block-button\"><div class=\"uagb-cta__wrap\"><h2 class=\"uagb-cta__title\">Instagram W&amp;L \u2013 Hochzeitsfotograf Langwieder See <\/h2><p class=\"uagb-cta__desc\">FOLGE MIR UND WERDE TEIL MEINER COMMUNITY!<\/p><\/div><div class=\"uagb-cta__buttons\"><a href=\"https:\/\/www.instagram.com\/whiteandlightphoto\/\" class=\"uagb-cta__button-link-wrapper wp-block-button__link\" target=\"_blank\" rel=\"noopener noreferrer\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>White and Light Instagram<\/a><\/div><\/div>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-color uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 alignfull uagb-block-9a6d37a8 uagb-columns__columns-4 uagb-columns__max_width-custom\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-4\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-6c79ea74\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-efee2b46 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-instagram_2.jpg \" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-instagram_2.jpg\" alt=\"hochzeitsfotograf instagram\" class=\"uag-image-8115\" width=\"700\" height=\"466\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-ae1ec349\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-b1473385 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-instagram_1.jpg \" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-instagram_1.jpg\" alt=\"hochzeitsfotograf instagram\" class=\"uag-image-8114\" width=\"700\" height=\"466\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-ddfe5a0c\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-3bb273b6 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-instagram_3.jpg \" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-instagram_3.jpg\" alt=\"hochzeitsfotograf instagram\" class=\"uag-image-8116\" width=\"700\" height=\"466\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-69a7d0f2\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-image uagb-block-5836722e wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-instagram_4.jpg \" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf-instagram_4.jpg\" alt=\"hochzeitsfotograf instagram\" class=\"uag-image-8123\" width=\"700\" height=\"466\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-14e36ddc\" id=\"hochzeitsfotograf-standesamt-Langwieder See\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d04a5abc\"><h2 class=\"uagb-heading-text\">Tipps f\u00fcr unvergessliche Hochzeitsfotos von fotograf Langwieder See<\/h2><p class=\"uagb-desc-text\">WICHTIGE INFORMATIONEN UND HILFREICHE TIPPS<\/p><\/div>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-3041ad92 uagb-columns__columns-3 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-a76120d3\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-920e8fd5\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-uagb-advanced-heading uagb-block-43d435ab\"><h3 class=\"uagb-heading-text\">Vorbereitung<\/h3><div class=\"uagb-separator\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0bc099e0\"><h3 class=\"uagb-heading-text\">Profi-Fotografen ausw\u00e4hlen | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Nehmt euch Zeit f\u00fcr die Recherche und vergleicht verschiedene Fotografen. Achtet auf Stil, Erfahrung und Preis. Besprecht in einem pers\u00f6nlichen Gespr\u00e4ch eure W\u00fcnsche und Erwartungen, um sicherzustellen, dass der Fotograf zu euch passt.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7502289c\"><h3 class=\"uagb-heading-text\">Hochzeits-Timeline erstellen | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Profi-Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Erstellt einen detaillierten Zeitplan f\u00fcr den Hochzeitstag, der gen\u00fcgend Zeit f\u00fcr Fotosessions einplannt. Ber\u00fccksichtigt dabei die Lichtverh\u00e4ltnisse an den verschiedenen Locations und Pufferzeiten f\u00fcr unvorhergesehene Ereignisse.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-841b7feb\"><h3 class=\"uagb-heading-text\">Details besprechen | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Renommierter Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Stellt dem Fotografen eine Liste mit euren W\u00fcnschen und Ideen f\u00fcr die Fotos zusammen. Dazu geh\u00f6ren z.B. bestimmte Gruppenfotos, Detailaufnahmen von Dekoration und Accessoires, sowie besondere Momente, die ihr festhalten m\u00f6chtet.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ad551d26\"><h3 class=\"uagb-heading-text\">Brautkleid &amp; Accessoires | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Hochzeitsfotograf mit Stilgef\u00fchl Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">W\u00e4hlt ein Kleid, das sich gut bewegt und beim Fotografieren vorteilhaft aussieht. Achtet auf bequeme Schuhe und passende Accessoires, die den Stil des Kleides unterstreichen.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f8894a30\"><h3 class=\"uagb-heading-text\">Brautstyling | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Moderner Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Make-up und Frisur sollten professionell gemacht werden und zum Kleid passen. Ein Probelauf vor der Hochzeit ist empfehlenswert, um sicherzustellen, dass alles perfekt sitzt und h\u00e4lt.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b803b3d5\"><h3 class=\"uagb-heading-text\">Am Hochzeitstag<\/h3><div class=\"uagb-separator\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f28c726d\"><h3 class=\"uagb-heading-text\">Entspannt bleiben | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Hochzeitsfotograf mit Know-how Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Es ist wichtig, dass ihr den Tag genie\u00dft und euch nicht vom Stress einholen lasst. Die Fotos werden umso sch\u00f6ner, wenn ihr entspannt und gut gelaunt seid.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-71bcf0a7\"><h3 class=\"uagb-heading-text\">Gute Laune | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Hochzeitsfotograf mit Erfahrung Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">L\u00e4chelt und habt Spa\u00df! Positive Stimmung und Freude spiegeln sich in den Fotos wider und machen sie zu einem unvergesslichen Andenken.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-548af73b\"><h3 class=\"uagb-heading-text\">Nat\u00fcrlichkeit bewahren | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Versucht nicht zu krampfhaft zu posieren. Die sch\u00f6nsten Fotos entstehen oft spontan und ungezwungen, wenn ihr einfach ihr selbst seid.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1327dbb4\"><h3 class=\"uagb-heading-text\">W\u00e4hrend der Fotoshootings<\/h3><div class=\"uagb-separator\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0e5c0890\"><h3 class=\"uagb-heading-text\">Verschiedene Locations nutzen | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Erfahrener Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">W\u00e4hlt abwechslungsreiche Orte f\u00fcr die Fotoshootings, um ein vielf\u00e4ltiges Bildportfolio zu erhalten. Nutzt die Umgebung kreativ und lasst euch von den Fotografen inspirieren.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5a5e74bc\"><h3 class=\"uagb-heading-text\">Gruppenfotos organisieren | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Innovativer Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Erstellt eine Liste mit gew\u00fcnschten Gruppenfotos und delegiert jemanden, der die G\u00e4ste zusammenbringt. So k\u00f6nnt ihr vermeiden, dass Zeit verloren geht und die Fotosession unn\u00f6tig lange dauert.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c73be005\"><h3 class=\"uagb-heading-text\">Paarfotos | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">K\u00fcnstlerischer Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Nehmt euch Zeit f\u00fcr ungest\u00f6rte Paarfotos, um eure Liebe und Zweisamkeit festzuhalten. Sucht euch daf\u00fcr ein ruhiges Pl\u00e4tzchen abseits des Trubels und genie\u00dft die Momente zu zweit.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-9ec213d5\"><h3 class=\"uagb-heading-text\">Details &amp; Momente | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Brautpaarfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Achtet auf kleine Details wie Ringe, Blumen und Dekoration. Die Fotos erz\u00e4hlen so die ganze Geschichte eures Hochzeitstages und werden zu einem wertvollen Erinnerungsst\u00fcck.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8c83d1fd\"><h3 class=\"uagb-heading-text\">Spa\u00df &amp; Emotionen | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Qualifizierter Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Seid locker und genie\u00dft die Zeit miteinander. Die Freude und Emotionen des Tages sollen auf den Fotos sichtbar sein und eure Liebe f\u00fcreinander widerspiegeln.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fe486cbe\"><h3 class=\"uagb-heading-text\">Ihr Hochzeitsfotograf im Langwieder See<\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Ich hoffe, diese Informationen helfen Ihnen bei der Planung Ihrer Hochzeit. Langwieder See bietet wundersch\u00f6ne Orte f\u00fcr Hochzeitsfotos. Herzlichen Gl\u00fcckwunsch zur bevorstehenden Hochzeit am Langwieder See!<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-6e4a1b9f\"><h3 class=\"uagb-heading-text\">Tipps f\u00fcr Posing<\/h3><div class=\"uagb-separator\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-77442164\"><h3 class=\"uagb-heading-text\">Sich aufrichten | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Hochzeitsfotograf mit Berufserfahrung Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Eine gute K\u00f6rperhaltung ist das A und O f\u00fcr jedes Foto. Stell dir vor, ein Faden w\u00fcrde dich an der Oberseite deines Kopfes nach oben ziehen. Die Schultern sollten zur\u00fcck und unten sein, der Brustkorb angehoben und der Bauchnabel eingezogen.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c2cb94f7\"><h3 class=\"uagb-heading-text\">Winkel | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Professioneller Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Nutze die Kraft der Winkel, um deine Figur zu strecken und deine besten Seiten zu betonen. Drehe deine H\u00fcften, Schultern und deinen Kopf leicht an, um dynamischere Posen zu erstellen.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-441b9f65\"><h3 class=\"uagb-heading-text\">Entspanne dein Gesicht | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Kreativer Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Ein verspanntes Gesicht wirkt unnat\u00fcrlich und kann deine Fotos ruinieren. Atme tief ein und l\u00e4chle entspannt.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-103156b9\"><h3 class=\"uagb-heading-text\">Selbstvertrauen | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Erfahrener Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Das Wichtigste ist, dass du an dich selbst glaubst. Wenn du dich gut f\u00fchlst, wird das auf deinen Fotos zu sehen sein.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fc601002\"><h3 class=\"uagb-heading-text\">Sei locker | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Stilvoller Hochzeitsfotograf Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Hab keine Angst, dich zu bewegen und verschiedene Posen auszuprobieren. Je lockerer du bist, desto nat\u00fcrlicher wirken deine Fotos. Probiere verschiedene Posen aus und finde heraus, was f\u00fcr dich am besten funktioniert. Es gibt keine festen Regeln beim Posing.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-9328718f\"><h3 class=\"uagb-heading-text\">Hab Spa\u00df! | <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ast-global-color-1-color\">Hochzeitsfotograf<\/mark> Langwieder See<\/mark><\/h3><\/div>\n\n\n\n<p class=\"has-small-font-size\">Am wichtigsten ist, dass du Spa\u00df am Shooting hast. Wenn du dich gut f\u00fchlst, wird das auf deinen Fotos zu sehen sein.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-8d7bab6c\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\t\t\t<div \n\t\t\tclass=\"wp-block-uagb-google-map uagb-google-map__wrap uagb-block-277cb211     \"\n\t\t\tstyle=\"\" >\n\t\t\t\t<embed\n\t\t\t\t\tclass=\"uagb-google-map__iframe\"\n\t\t\t\t\ttitle=\"Google Map for \"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Langwieder%20See&#038;z=12&#038;hl=de&#038;t=m&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\twidth=\"640\"\n\t\t\t\t\theight=\"600\"\n\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t><\/embed>\n\t\t\t<\/div>\n\t\t\t","protected":false},"excerpt":{"rendered":"<p>Sie inspirieren mich! 15 JAHREHOCHZEITSERFAHRUNG 500 198 GESTALTETEHOCHZEITSFOTOB\u00dcCHER 21.600 AUSBELICHTETEFOTOABZ\u00dcGE<\/p>\n","protected":false},"author":1,"featured_media":10742,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"disabled","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-12385","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hochzeitsfotograf Langwieder See<\/title>\n<meta name=\"description\" content=\"Hi, ich bin Andrej, Ihr Hochzeitsfotograf am Langwieder See. Kreative, sinnliche und lebendige Hochzeitsfotos voller Liebe und Lachen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hochzeitsfotograf M\u00fcnchen White and Light - Hochzeitsfotografie\" \/>\n<meta property=\"og:description\" content=\"Hochzeitsfotograf in M\u00fcnchen f\u00fcr emotionale Hochzeitsreportagen und nat\u00fcrliche Hochzeitsportraits. Professionelle und kreative Arbeitsweise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/\" \/>\n<meta property=\"og:site_name\" content=\"Hochzeitsfotograf\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WhiteAndLightHochzeitsfotografMuenchen\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T06:23:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-e1608203281749.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"813\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Hochzeitsfotograf M\u00fcnchen White and Light - Hochzeitsfotografie\" \/>\n<meta name=\"twitter:description\" content=\"Hochzeitsfotograf in M\u00fcnchen f\u00fcr emotionale Hochzeitsreportagen und nat\u00fcrliche Hochzeitsportraits. Professionelle und kreative Arbeitsweise.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-e1608203281749.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@whiteandlightde\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"26\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/\",\"name\":\"Hochzeitsfotograf Langwieder See\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp\",\"datePublished\":\"2024-03-28T10:12:31+00:00\",\"dateModified\":\"2024-05-02T06:23:39+00:00\",\"description\":\"Hi, ich bin Andrej, Ihr Hochzeitsfotograf am Langwieder See. Kreative, sinnliche und lebendige Hochzeitsfotos voller Liebe und Lachen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp\",\"contentUrl\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp\",\"width\":1200,\"height\":675,\"caption\":\"Hochzeitsfotograf M\u00fcnchen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hochzeitsfotograf Langwieder See \u2013 Die Kunst der emotionalen Bildsprache\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/#website\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/\",\"name\":\"Hochzeitsfotograf M\u00fcnchen \u2013 Lebendige und ungestellte Hochzeitsfotos voller Emotionen\",\"description\":\"Hochzeitsfotograf White and Light  \u2013 Ungestellte und emotionale Hochzeitsfotos\",\"publisher\":{\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/#organization\"},\"alternateName\":\"Hochzeitsfotograf M\u00fcnchen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/#organization\",\"name\":\"Hochzeitsfotograf M\u00fcnchen \u2013 White and Light\",\"alternateName\":\"Hochzeitsfotograf M\u00fcnchen\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/hochzeitsfotograf_muenchen.png\",\"contentUrl\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/hochzeitsfotograf_muenchen.png\",\"width\":512,\"height\":512,\"caption\":\"Hochzeitsfotograf M\u00fcnchen \u2013 White and Light\"},\"image\":{\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WhiteAndLightHochzeitsfotografMuenchen\\\/\",\"https:\\\/\\\/x.com\\\/whiteandlightde\",\"https:\\\/\\\/www.instagram.com\\\/whiteandlightphoto\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/whiteandlightphoto\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/whiteandlightphoto\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@whiteandlightphoto\",\"https:\\\/\\\/whiteandlightphoto.tumblr.com\\\/\",\"https:\\\/\\\/flickr.com\\\/photos\\\/andreynikolaev\",\"https:\\\/\\\/500px.com\\\/p\\\/andrey_nikolaev\",\"https:\\\/\\\/andreynikolaev.livejournal.com\\\/\",\"https:\\\/\\\/de.foursquare.com\\\/whiteandlightde\",\"https:\\\/\\\/vimeo.com\\\/235027912\",\"https:\\\/\\\/heirate.in\\\/hochzeitsdienstleister\\\/andrey-nikolaev\\\/\",\"https:\\\/\\\/bridebook.com\\\/de\\\/wedding-photographers\\\/white-and-light-m-nchen-upper-bavaria-deqYNqq2gV\",\"https:\\\/\\\/trustlocal.de\\\/bayern\\\/m\u00fcnchen\\\/fotograf\\\/hochzeitsfotograf-munchen-white-and-light\\\/\",\"https:\\\/\\\/www.hochzeitsfotograf.com\\\/fotografen\\\/profil\\\/20437\\\/andrey\",\"https:\\\/\\\/www.yelp.de\\\/biz\\\/white-and-light-m\u00fcnchen\",\"http:\\\/\\\/www.fotografensuche.de\\\/fotograf-muenchen\\\/hochzeitsfotograf-andrey-nikolaev-f8260\",\"https:\\\/\\\/www.berufsfotografen.com\\\/white-and-light-81379-muenchen\\\/5971\",\"https:\\\/\\\/events.check24.de\\\/events\\\/cs\\\/profile\\\/sp_8n27E\",\"https:\\\/\\\/youpic.com\\\/whiteandlight\\\/\",\"https:\\\/\\\/www.hochzeitsportal24.de\\\/branchenbuch\\\/hochzeitsfotos\\\/white-and-light-whiteandlightcom-muenchen\\\/\",\"https:\\\/\\\/mywed.com\\\/de\\\/photographer\\\/munich\\\/\",\"https:\\\/\\\/www.hochzeitsideen-muenchen.de\\\/fotografen\\\/white-and-light-wedding-photography-muenchen\",\"https:\\\/\\\/fstoppers.com\\\/profile\\\/muenchenhochzeitsfotograf\",\"https:\\\/\\\/hochzeits-fotograf.info\\\/hochzeitsfotograf\\\/white-and-light-hochzeitsfotografie-in-munchen-von-andrey-nikolaev\",\"https:\\\/\\\/www.fotocommunity.de\\\/fotograf\\\/andrey-nikolajew\\\/499497\",\"https:\\\/\\\/muenchen24.ru\\\/de\\\/firm\\\/bankety-svadby-torzestva\\\/foto-i-videosemka-in-munchen\\\/505-509\\\/9705.html\",\"https:\\\/\\\/hochzeitsfotograf.medium.com\\\/\",\"https:\\\/\\\/www.zankyou.de\\\/f\\\/hochzeitsfotograf-andrej-nikolajew-63031\",\"https:\\\/\\\/3pulse.com\\\/AndrejNikolajew\\\/\",\"http:\\\/\\\/www.findglocal.com\\\/DE\\\/Munich\\\/233886107022493\\\/Andrey-Nikolaev---Munich-wedding-photographer\",\"https:\\\/\\\/www.fixando.de\\\/profil\\\/555\\\/whiteandlightndashhochzeitsfotografie\",\"https:\\\/\\\/www.golocal.de\\\/muenchen\\\/foto\\\/hochzeitsfotograf-in-muenchen-white-and-light-Np1sY\\\/\",\"https:\\\/\\\/www.model-kartei.de\\\/sedcards\\\/photographer\\\/197713\\\/andrey-nikolaev\\\/\",\"https:\\\/\\\/www.goyellow.de\\\/home\\\/hochzeitsservice-hochzeitsfotograf-in-muenchen-white-and-light-muenchen--lcq6b.html\",\"https:\\\/\\\/www.gelbeseiten.de\\\/gsbiz\\\/68b8292a-7a53-4ba6-82d7-aa3a747298ba\",\"https:\\\/\\\/www.dasoertliche.de\\\/?form_name=detail&id=2247103824189&recuid=6ZDXXLF3G4EZ6LEZ7J2IU6HUW67RTYRIZB4UMMVAJXWFTBIDMABA&niceid=Nikolajew-Andrej-M\u00fcnchen-Thalkirchen-Am-Isarkanal&verlNr=120&buc=2247&hitno=0&showbuc=0&kw=Nikolajew Andrej&ci=M\u00fcnchen\",\"https:\\\/\\\/www.provenexpert.com\\\/de-de\\\/white-and-light\\\/\",\"https:\\\/\\\/www.xing.com\\\/profile\\\/Andrey_Nikolaev6\",\"https:\\\/\\\/web2.cylex.de\\\/firma-home\\\/white-and-light-14138323.html\",\"https:\\\/\\\/finde-offen.de\\\/muenchen\\\/white-and-light-4063963\",\"https:\\\/\\\/www.kuenstlerstadt.de\\\/profile\\\/white-and-light-hochzeitsfotograf-in-muenchen\",\"https:\\\/\\\/www.misterwhat.de\\\/company\\\/2677930-hochzeitsfotografru-muenchen\",\"https:\\\/\\\/www.finderr.de\\\/whiteandlight.com\\\/hochzeitsfotograf-hochzeitsfotograf-fotograf-muenchen-white-and-light-450528\",\"https:\\\/\\\/www.hochzeit-selber-planen.com\\\/listing-item\\\/andrey-nikolaev-white-and-light-photography\\\/\",\"https:\\\/\\\/www.webwiki.de\\\/whiteandlight.com\\\/hochzeitsfotograf\",\"https:\\\/\\\/www.kennstdueinen.de\\\/fotograf-muenchen-hochzeitsfotograf-muenchen-d355457.html\",\"https:\\\/\\\/www.hochzeit.com\\\/verzeichnis\\\/18793\\\/white-and-light-wedding-photography-hochzeitsfotograf-muenchen\\\/\",\"https:\\\/\\\/www.werkenntdenbesten.de\\\/e\\\/105727624\\\/fotoatelier\\\/muenchen\\\/hochzeitsfotograf-muenchen-white-and-light-bewertungen\",\"https:\\\/\\\/www.theperfectwedding.de\\\/dienstleister\\\/229537\\\/white-and-light\"]},{\"@type\":\"HowTo\",\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#howto-1\",\"name\":\"Hochzeitsfotograf Langwieder See \u2013 Die Kunst der emotionalen Bildsprache\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/\"},\"description\":\"DIE WICHTIGSTEN PUNKTE IM \u00dcBERBLICK\",\"step\":[{\"@type\":\"HowToStep\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#how-to-step-1711372022508\",\"name\":\"Anfrage\",\"itemListElement\":[{\"@type\":\"HowToDirection\",\"text\":\"Nehmen Sie Kontakt mit mir auf \u2013 entweder \u00fcber meine Website oder per E-Mail. Teilen Sie mir Ihr Hochzeitsdatum und den Veranstaltungsort mit.\"}]},{\"@type\":\"HowToStep\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#how-to-step-1711372061753\",\"name\":\"Angebot\",\"itemListElement\":[{\"@type\":\"HowToDirection\",\"text\":\"Ich erstelle ein individuelles Angebot und sende es Ihnen zu.\"}]},{\"@type\":\"HowToStep\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#how-to-step-1711372167394\",\"name\":\"Kennenlernengespr\u00e4ch\",\"itemListElement\":[{\"@type\":\"HowToDirection\",\"text\":\"In einem pers\u00f6nlichen Gespr\u00e4ch per WhatsApp-Videoanruf oder in meinem B\u00fcro besprechen wir Ihre W\u00fcnsche und Vorstellungen f\u00fcr die fotografische Begleitung.\"}]},{\"@type\":\"HowToStep\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#how-to-step-1711372187195\",\"name\":\"Buchung\",\"itemListElement\":[{\"@type\":\"HowToDirection\",\"text\":\"Sobald wir alle Details besprochen haben, erhalten Sie von mir einen Vertrag. Nach schriftlicher Zustimmung zum Vertrag bin ich f\u00fcr Sie gebucht.\"}]},{\"@type\":\"HowToStep\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#how-to-step-1711372209273\",\"name\":\"Hochzeitstag\",\"itemListElement\":[{\"@type\":\"HowToDirection\",\"text\":\"Am Hochzeitstag bin ich p\u00fcnktlich vor Ort und werde jeden besonderen Moment in einzigartigen Bildern festhalten. Dabei arbeite ich dezent und professionell, um den Ablauf Ihrer Feier so wenig wie m\u00f6glich zu st\u00f6ren.\"}]},{\"@type\":\"HowToStep\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#how-to-step-1711372222021\",\"name\":\"Bildbearbeitung\",\"itemListElement\":[{\"@type\":\"HowToDirection\",\"text\":\"Nach der Hochzeit bearbeite ich die Fotos sorgf\u00e4ltig, so erhalten Sie von mir hochwertige Bilder, die Ihre Hochzeit in bester Erinnerung behalten werden.\"}]},{\"@type\":\"HowToStep\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#how-to-step-1711372240103\",\"name\":\"Bild\u00fcbergabe\",\"itemListElement\":[{\"@type\":\"HowToDirection\",\"text\":\"Die fertigen Fotos erhalten Sie in hoher Aufl\u00f6sung auf einem USB-Stick \u2013 sowohl in Farbe als auch in Schwarz-Wei\u00df und 40 von mir ausgew\u00e4hlte, ausbelichtete Fotoabz\u00fcge. Dar\u00fcber hinaus stelle ich Ihnen eine Online-Galerie zur Verf\u00fcgung, von der Ihre Familie und Freunde die Bilder bequem herunterladen k\u00f6nnen.\"}]},{\"@type\":\"HowToStep\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#how-to-step-1711372251700\",\"name\":\"Bezahlung\",\"itemListElement\":[{\"@type\":\"HowToDirection\",\"text\":\"Die Rechnung erhalten Sie zusammen mit den Fotos. Der Betrag wird nach Erhalt der Rechnung f\u00e4llig.\"}]},{\"@type\":\"HowToStep\",\"url\":\"https:\\\/\\\/whiteandlight.com\\\/hochzeitsfotograf\\\/hochzeitsfotograf-langwieder-see\\\/#how-to-step-1711390196442\",\"name\":\"Feedback\",\"itemListElement\":[{\"@type\":\"HowToDirection\",\"text\":\"Ihre Zufriedenheit ist mir sehr wichtig. Wenn Sie mit meiner Arbeit als Hochzeitsfotograf zufrieden waren, w\u00fcrde ich mich \u00fcber Ihr Feedback und eine Bewertung auf Google Maps freuen.\"}]}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hochzeitsfotograf Langwieder See","description":"Hi, ich bin Andrej, Ihr Hochzeitsfotograf am Langwieder See. Kreative, sinnliche und lebendige Hochzeitsfotos voller Liebe und Lachen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/","og_locale":"de_DE","og_type":"article","og_title":"Hochzeitsfotograf M\u00fcnchen White and Light - Hochzeitsfotografie","og_description":"Hochzeitsfotograf in M\u00fcnchen f\u00fcr emotionale Hochzeitsreportagen und nat\u00fcrliche Hochzeitsportraits. Professionelle und kreative Arbeitsweise.","og_url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/","og_site_name":"Hochzeitsfotograf","article_publisher":"https:\/\/www.facebook.com\/WhiteAndLightHochzeitsfotografMuenchen\/","article_modified_time":"2024-05-02T06:23:39+00:00","og_image":[{"width":1500,"height":813,"url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-e1608203281749.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Hochzeitsfotograf M\u00fcnchen White and Light - Hochzeitsfotografie","twitter_description":"Hochzeitsfotograf in M\u00fcnchen f\u00fcr emotionale Hochzeitsreportagen und nat\u00fcrliche Hochzeitsportraits. Professionelle und kreative Arbeitsweise.","twitter_image":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-e1608203281749.jpg","twitter_site":"@whiteandlightde","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"26\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/","name":"Hochzeitsfotograf Langwieder See","isPartOf":{"@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#primaryimage"},"image":{"@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#primaryimage"},"thumbnailUrl":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp","datePublished":"2024-03-28T10:12:31+00:00","dateModified":"2024-05-02T06:23:39+00:00","description":"Hi, ich bin Andrej, Ihr Hochzeitsfotograf am Langwieder See. Kreative, sinnliche und lebendige Hochzeitsfotos voller Liebe und Lachen.","breadcrumb":{"@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#primaryimage","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp","contentUrl":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp","width":1200,"height":675,"caption":"Hochzeitsfotograf M\u00fcnchen"},{"@type":"BreadcrumbList","@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/"},{"@type":"ListItem","position":2,"name":"Hochzeitsfotograf Langwieder See \u2013 Die Kunst der emotionalen Bildsprache"}]},{"@type":"WebSite","@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/#website","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/","name":"Hochzeitsfotograf M\u00fcnchen \u2013 Lebendige und ungestellte Hochzeitsfotos voller Emotionen","description":"Hochzeitsfotograf White and Light  \u2013 Ungestellte und emotionale Hochzeitsfotos","publisher":{"@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/#organization"},"alternateName":"Hochzeitsfotograf M\u00fcnchen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/#organization","name":"Hochzeitsfotograf M\u00fcnchen \u2013 White and Light","alternateName":"Hochzeitsfotograf M\u00fcnchen","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/#\/schema\/logo\/image\/","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen.png","contentUrl":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_muenchen.png","width":512,"height":512,"caption":"Hochzeitsfotograf M\u00fcnchen \u2013 White and Light"},"image":{"@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WhiteAndLightHochzeitsfotografMuenchen\/","https:\/\/x.com\/whiteandlightde","https:\/\/www.instagram.com\/whiteandlightphoto\/","https:\/\/www.linkedin.com\/in\/whiteandlightphoto\/","https:\/\/www.pinterest.de\/whiteandlightphoto\/","https:\/\/www.youtube.com\/@whiteandlightphoto","https:\/\/whiteandlightphoto.tumblr.com\/","https:\/\/flickr.com\/photos\/andreynikolaev","https:\/\/500px.com\/p\/andrey_nikolaev","https:\/\/andreynikolaev.livejournal.com\/","https:\/\/de.foursquare.com\/whiteandlightde","https:\/\/vimeo.com\/235027912","https:\/\/heirate.in\/hochzeitsdienstleister\/andrey-nikolaev\/","https:\/\/bridebook.com\/de\/wedding-photographers\/white-and-light-m-nchen-upper-bavaria-deqYNqq2gV","https:\/\/trustlocal.de\/bayern\/m\u00fcnchen\/fotograf\/hochzeitsfotograf-munchen-white-and-light\/","https:\/\/www.hochzeitsfotograf.com\/fotografen\/profil\/20437\/andrey","https:\/\/www.yelp.de\/biz\/white-and-light-m\u00fcnchen","http:\/\/www.fotografensuche.de\/fotograf-muenchen\/hochzeitsfotograf-andrey-nikolaev-f8260","https:\/\/www.berufsfotografen.com\/white-and-light-81379-muenchen\/5971","https:\/\/events.check24.de\/events\/cs\/profile\/sp_8n27E","https:\/\/youpic.com\/whiteandlight\/","https:\/\/www.hochzeitsportal24.de\/branchenbuch\/hochzeitsfotos\/white-and-light-whiteandlightcom-muenchen\/","https:\/\/mywed.com\/de\/photographer\/munich\/","https:\/\/www.hochzeitsideen-muenchen.de\/fotografen\/white-and-light-wedding-photography-muenchen","https:\/\/fstoppers.com\/profile\/muenchenhochzeitsfotograf","https:\/\/hochzeits-fotograf.info\/hochzeitsfotograf\/white-and-light-hochzeitsfotografie-in-munchen-von-andrey-nikolaev","https:\/\/www.fotocommunity.de\/fotograf\/andrey-nikolajew\/499497","https:\/\/muenchen24.ru\/de\/firm\/bankety-svadby-torzestva\/foto-i-videosemka-in-munchen\/505-509\/9705.html","https:\/\/hochzeitsfotograf.medium.com\/","https:\/\/www.zankyou.de\/f\/hochzeitsfotograf-andrej-nikolajew-63031","https:\/\/3pulse.com\/AndrejNikolajew\/","http:\/\/www.findglocal.com\/DE\/Munich\/233886107022493\/Andrey-Nikolaev---Munich-wedding-photographer","https:\/\/www.fixando.de\/profil\/555\/whiteandlightndashhochzeitsfotografie","https:\/\/www.golocal.de\/muenchen\/foto\/hochzeitsfotograf-in-muenchen-white-and-light-Np1sY\/","https:\/\/www.model-kartei.de\/sedcards\/photographer\/197713\/andrey-nikolaev\/","https:\/\/www.goyellow.de\/home\/hochzeitsservice-hochzeitsfotograf-in-muenchen-white-and-light-muenchen--lcq6b.html","https:\/\/www.gelbeseiten.de\/gsbiz\/68b8292a-7a53-4ba6-82d7-aa3a747298ba","https:\/\/www.dasoertliche.de\/?form_name=detail&id=2247103824189&recuid=6ZDXXLF3G4EZ6LEZ7J2IU6HUW67RTYRIZB4UMMVAJXWFTBIDMABA&niceid=Nikolajew-Andrej-M\u00fcnchen-Thalkirchen-Am-Isarkanal&verlNr=120&buc=2247&hitno=0&showbuc=0&kw=Nikolajew Andrej&ci=M\u00fcnchen","https:\/\/www.provenexpert.com\/de-de\/white-and-light\/","https:\/\/www.xing.com\/profile\/Andrey_Nikolaev6","https:\/\/web2.cylex.de\/firma-home\/white-and-light-14138323.html","https:\/\/finde-offen.de\/muenchen\/white-and-light-4063963","https:\/\/www.kuenstlerstadt.de\/profile\/white-and-light-hochzeitsfotograf-in-muenchen","https:\/\/www.misterwhat.de\/company\/2677930-hochzeitsfotografru-muenchen","https:\/\/www.finderr.de\/whiteandlight.com\/hochzeitsfotograf-hochzeitsfotograf-fotograf-muenchen-white-and-light-450528","https:\/\/www.hochzeit-selber-planen.com\/listing-item\/andrey-nikolaev-white-and-light-photography\/","https:\/\/www.webwiki.de\/whiteandlight.com\/hochzeitsfotograf","https:\/\/www.kennstdueinen.de\/fotograf-muenchen-hochzeitsfotograf-muenchen-d355457.html","https:\/\/www.hochzeit.com\/verzeichnis\/18793\/white-and-light-wedding-photography-hochzeitsfotograf-muenchen\/","https:\/\/www.werkenntdenbesten.de\/e\/105727624\/fotoatelier\/muenchen\/hochzeitsfotograf-muenchen-white-and-light-bewertungen","https:\/\/www.theperfectwedding.de\/dienstleister\/229537\/white-and-light"]},{"@type":"HowTo","@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#howto-1","name":"Hochzeitsfotograf Langwieder See \u2013 Die Kunst der emotionalen Bildsprache","mainEntityOfPage":{"@id":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/"},"description":"DIE WICHTIGSTEN PUNKTE IM \u00dcBERBLICK","step":[{"@type":"HowToStep","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#how-to-step-1711372022508","name":"Anfrage","itemListElement":[{"@type":"HowToDirection","text":"Nehmen Sie Kontakt mit mir auf \u2013 entweder \u00fcber meine Website oder per E-Mail. Teilen Sie mir Ihr Hochzeitsdatum und den Veranstaltungsort mit."}]},{"@type":"HowToStep","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#how-to-step-1711372061753","name":"Angebot","itemListElement":[{"@type":"HowToDirection","text":"Ich erstelle ein individuelles Angebot und sende es Ihnen zu."}]},{"@type":"HowToStep","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#how-to-step-1711372167394","name":"Kennenlernengespr\u00e4ch","itemListElement":[{"@type":"HowToDirection","text":"In einem pers\u00f6nlichen Gespr\u00e4ch per WhatsApp-Videoanruf oder in meinem B\u00fcro besprechen wir Ihre W\u00fcnsche und Vorstellungen f\u00fcr die fotografische Begleitung."}]},{"@type":"HowToStep","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#how-to-step-1711372187195","name":"Buchung","itemListElement":[{"@type":"HowToDirection","text":"Sobald wir alle Details besprochen haben, erhalten Sie von mir einen Vertrag. Nach schriftlicher Zustimmung zum Vertrag bin ich f\u00fcr Sie gebucht."}]},{"@type":"HowToStep","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#how-to-step-1711372209273","name":"Hochzeitstag","itemListElement":[{"@type":"HowToDirection","text":"Am Hochzeitstag bin ich p\u00fcnktlich vor Ort und werde jeden besonderen Moment in einzigartigen Bildern festhalten. Dabei arbeite ich dezent und professionell, um den Ablauf Ihrer Feier so wenig wie m\u00f6glich zu st\u00f6ren."}]},{"@type":"HowToStep","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#how-to-step-1711372222021","name":"Bildbearbeitung","itemListElement":[{"@type":"HowToDirection","text":"Nach der Hochzeit bearbeite ich die Fotos sorgf\u00e4ltig, so erhalten Sie von mir hochwertige Bilder, die Ihre Hochzeit in bester Erinnerung behalten werden."}]},{"@type":"HowToStep","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#how-to-step-1711372240103","name":"Bild\u00fcbergabe","itemListElement":[{"@type":"HowToDirection","text":"Die fertigen Fotos erhalten Sie in hoher Aufl\u00f6sung auf einem USB-Stick \u2013 sowohl in Farbe als auch in Schwarz-Wei\u00df und 40 von mir ausgew\u00e4hlte, ausbelichtete Fotoabz\u00fcge. Dar\u00fcber hinaus stelle ich Ihnen eine Online-Galerie zur Verf\u00fcgung, von der Ihre Familie und Freunde die Bilder bequem herunterladen k\u00f6nnen."}]},{"@type":"HowToStep","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#how-to-step-1711372251700","name":"Bezahlung","itemListElement":[{"@type":"HowToDirection","text":"Die Rechnung erhalten Sie zusammen mit den Fotos. Der Betrag wird nach Erhalt der Rechnung f\u00e4llig."}]},{"@type":"HowToStep","url":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/hochzeitsfotograf-langwieder-see\/#how-to-step-1711390196442","name":"Feedback","itemListElement":[{"@type":"HowToDirection","text":"Ihre Zufriedenheit ist mir sehr wichtig. Wenn Sie mit meiner Arbeit als Hochzeitsfotograf zufrieden waren, w\u00fcrde ich mich \u00fcber Ihr Feedback und eine Bewertung auf Google Maps freuen."}]}],"inLanguage":"de"}]}},"spectra_custom_meta":{"site-post-title":["disabled"],"site-sidebar-layout":["default"],"site-content-layout":["default"],"ast-featured-img":["disabled"],"ast-breadcrumbs-content":["disabled"],"theme-transparent-header-meta":["default"],"_yoast_wpseo_focuskw":["Hochzeitsfotograf Langwieder See"],"_yoast_wpseo_title":["Hochzeitsfotograf Langwieder See"],"_yoast_wpseo_metadesc":["Hi, ich bin Andrej, Ihr Hochzeitsfotograf am Langwieder See. Kreative, sinnliche und lebendige Hochzeitsfotos voller Liebe und Lachen."],"_yoast_wpseo_linkdex":["83"],"_yoast_wpseo_estimated-reading-time-minutes":["26"],"_yoast_wpseo_wordproof_timestamp":[""],"_yoast_wpseo_opengraph-title":["Hochzeitsfotograf M\u00fcnchen White and Light - Hochzeitsfotografie"],"_yoast_wpseo_opengraph-description":["Hochzeitsfotograf in M\u00fcnchen f\u00fcr emotionale Hochzeitsreportagen und nat\u00fcrliche Hochzeitsportraits. Professionelle und kreative Arbeitsweise."],"_yoast_wpseo_opengraph-image":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-e1608203281749.jpg"],"_yoast_wpseo_opengraph-image-id":["1137"],"_yoast_wpseo_twitter-title":["Hochzeitsfotograf M\u00fcnchen White and Light - Hochzeitsfotografie"],"_yoast_wpseo_twitter-description":["Hochzeitsfotograf in M\u00fcnchen f\u00fcr emotionale Hochzeitsreportagen und nat\u00fcrliche Hochzeitsportraits. Professionelle und kreative Arbeitsweise."],"_yoast_wpseo_twitter-image":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-e1608203281749.jpg"],"_yoast_wpseo_twitter-image-id":["1137"],"footnotes":[""],"_uag_custom_page_level_css":[""],"ast-site-content-layout":["default"],"adv-header-id-meta":[""],"stick-header-meta":[""],"astra-migrate-meta-layouts":["set"],"_yoast_wpseo_meta-robots-noindex":["2"],"_vp_words_count":["757"],"litespeed_vpi_list":["a:2:{i:0;s:43:\"hochzeitsfotograf_muenchen_weiss-150x21.png\";i:1;s:40:\"Hochzeitsfotograf_Muenchen_2024_Anna.jpg\";}"],"_thumbnail_id":["10742"],"_vp_format_video_url":[""],"_vp_image_focal_point":["a:2:{s:1:\"x\";d:0.5;s:1:\"y\";d:0.5;}"],"yoast-structured-data-blocks-images-cache":["a:0:{}"],"_dp_original":["12383"],"_edit_lock":["1714631025:1"],"_edit_last":["1"],"hreflang-de":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/"],"wp_featherlight_disable":[""],"_uagb_toc_options":["a:2:{s:17:\"_uagb_toc_version\";s:10:\"1774528264\";s:18:\"_uagb_toc_headings\";a:80:{i:0;a:4:{s:5:\"level\";i:1;s:2:\"id\";s:32:\"hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:32:\"Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:1;}i:1;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:48:\"hi-ich-bin-andrej-ihr-fotograf-am-langwieder-see\";s:7:\"content\";s:50:\"Hi, ich bin Andrej, Ihr Fotograf am Langwieder See\";s:5:\"depth\";i:2;}i:2;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:71:\"einblicke-in-meine-hochzeitsreportagen-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:73:\"Einblicke in meine Hochzeitsreportagen | Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:2;}i:3;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:22:\"m\u00e4rchenhafte-hochzeit\";s:7:\"content\";s:22:\"M\u00e4rchenhafte Hochzeit\";s:5:\"depth\";i:3;}i:4;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:20:\"romantische-hochzeit\";s:7:\"content\";s:20:\"Romantische Hochzeit\";s:5:\"depth\";i:3;}i:5;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:33:\"hochzeit-in-goldenen-herbstt\u00f6nen\";s:7:\"content\";s:33:\"Hochzeit in goldenen Herbstt\u00f6nen\";s:5:\"depth\";i:3;}i:6;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:18:\"kirchliche-trauung\";s:7:\"content\";s:18:\"Kirchliche Trauung\";s:5:\"depth\";i:3;}i:7;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:50:\"rustikales-ambiente-f\u00fcr-eine-gem\u00fctliche-hochzeit\";s:7:\"content\";s:50:\"Rustikales Ambiente f\u00fcr eine gem\u00fctliche Hochzeit\";s:5:\"depth\";i:3;}i:8;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:23:\"ein-erf\u00fclltes-m\u00e4rchen\";s:7:\"content\";s:23:\"Ein erf\u00fclltes M\u00e4rchen\";s:5:\"depth\";i:3;}i:9;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:21:\"hochzeit-am-ozeanufer\";s:7:\"content\";s:21:\"Hochzeit am Ozeanufer\";s:5:\"depth\";i:3;}i:10;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:24:\"standesamtliche-hochzeit\";s:7:\"content\";s:24:\"Standesamtliche Hochzeit\";s:5:\"depth\";i:3;}i:11;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:31:\"hochzeit-im-oberbayrischen-land\";s:7:\"content\";s:31:\"Hochzeit im oberbayrischen Land\";s:5:\"depth\";i:3;}i:12;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:18:\"zweimal-das-jawort\";s:7:\"content\";s:18:\"Zweimal das Jawort\";s:5:\"depth\";i:3;}i:13;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:16:\"herzliche-w\u00e4rme\";s:7:\"content\";s:16:\"Herzliche W\u00e4rme\";s:5:\"depth\";i:3;}i:14;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:47:\"wer-sagt-dass-eine-braut-in-wei\u00df-heiraten-muss\";s:7:\"content\";s:49:\"Wer sagt, dass eine Braut in Wei\u00df heiraten muss?\";s:5:\"depth\";i:3;}i:15;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:46:\"hochzeitspakethochzeitsfotograf-langwieder-see\";s:7:\"content\";s:46:\"HochzeitspaketHochzeitsfotograf Langwieder See\";s:5:\"depth\";i:2;}i:16;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:8:\"beratung\";s:7:\"content\";s:8:\"Beratung\";s:5:\"depth\";i:3;}i:17;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:12:\"paarshooting\";s:7:\"content\";s:12:\"Paarshooting\";s:5:\"depth\";i:3;}i:18;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:8:\"80-fotos\";s:7:\"content\";s:8:\"80 Fotos\";s:5:\"depth\";i:3;}i:19;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:15:\"nachbearbeitung\";s:7:\"content\";s:15:\"Nachbearbeitung\";s:5:\"depth\";i:3;}i:20;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:13:\"fotos-auf-usb\";s:7:\"content\";s:13:\"Fotos auf USB\";s:5:\"depth\";i:3;}i:21;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:14:\"40-fotoabz\u00fcge\";s:7:\"content\";s:14:\"40 Fotoabz\u00fcge\";s:5:\"depth\";i:3;}i:22;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:14:\"online-galerie\";s:7:\"content\";s:14:\"Online-Galerie\";s:5:\"depth\";i:3;}i:23;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:17:\"fotos-in-2-wochen\";s:7:\"content\";s:17:\"Fotos in 2 Wochen\";s:5:\"depth\";i:3;}i:24;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:14:\"nutzungsrechte\";s:7:\"content\";s:14:\"Nutzungsrechte\";s:5:\"depth\";i:3;}i:25;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:19:\"flexible-begleitung\";s:7:\"content\";s:19:\"Flexible Begleitung\";s:5:\"depth\";i:3;}i:26;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:21:\"reisekosten-inklusive\";s:7:\"content\";s:21:\"Reisekosten inklusive\";s:5:\"depth\";i:3;}i:27;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:19:\"keine-vorauszahlung\";s:7:\"content\";s:19:\"Keine Vorauszahlung\";s:5:\"depth\";i:3;}i:28;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:69:\"ein-blick-hinter-die-kulissen-von-wl-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:74:\"Ein Blick hinter die Kulissen von W&L \u2013 Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:2;}i:29;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:27:\"10k-followers-auf-instagram\";s:7:\"content\";s:27:\"10K Followers auf Instagram\";s:5:\"depth\";i:3;}i:30;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:34:\"brautstrau\u00df-spiegelbild-der-braut\";s:7:\"content\";s:38:\"Brautstrau\u00df \u2013 Spiegelbild der Braut\";s:5:\"depth\";i:3;}i:31;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:19:\"kamera-kaufberatung\";s:7:\"content\";s:19:\"Kamera Kaufberatung\";s:5:\"depth\";i:3;}i:32;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:16:\"liebe-zum-detail\";s:7:\"content\";s:16:\"Liebe zum Detail\";s:5:\"depth\";i:3;}i:33;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:20:\"preisgekr\u00f6ntes-foto\";s:7:\"content\";s:20:\"Preisgekr\u00f6ntes Foto\";s:5:\"depth\";i:3;}i:34;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:23:\"symbol-der-ewigen-liebe\";s:7:\"content\";s:23:\"Symbol der ewigen Liebe\";s:5:\"depth\";i:3;}i:35;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:33:\"checkliste-f\u00fcr-portr\u00e4taufnahmen\";s:7:\"content\";s:33:\"Checkliste f\u00fcr Portr\u00e4taufnahmen\";s:5:\"depth\";i:3;}i:36;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:30:\"tipp-f\u00fcr-die-hochzeitsplanung\";s:7:\"content\";s:30:\"Tipp f\u00fcr die Hochzeitsplanung\";s:5:\"depth\";i:3;}i:37;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:56:\"hochzeitspaare-\u00fcber-wl-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:59:\"Hochzeitspaare \u00fcber W&L - Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:2;}i:38;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:13:\"julia-michael\";s:7:\"content\";s:15:\"Julia & Michael\";s:5:\"depth\";i:3;}i:39;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:24:\"bester-hochzeitsfotograf\";s:7:\"content\";s:24:\"Bester Hochzeitsfotograf\";s:5:\"depth\";i:3;}i:40;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:24:\"bilder-sind-sensationell\";s:7:\"content\";s:24:\"Bilder sind sensationell\";s:5:\"depth\";i:3;}i:41;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:33:\"hoch-professionelle-kommunikation\";s:7:\"content\";s:33:\"Hoch professionelle Kommunikation\";s:5:\"depth\";i:3;}i:42;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:54:\"andrej-bringt-viel-gute-laune-und-positive-energie-mit\";s:7:\"content\";s:54:\"Andrej bringt viel gute Laune und positive Energie mit\";s:5:\"depth\";i:3;}i:43;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:34:\"supersch\u00f6ne-und-nat\u00fcrliche-fotos\";s:7:\"content\";s:34:\"Supersch\u00f6ne und nat\u00fcrliche Fotos\";s:5:\"depth\";i:3;}i:44;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:44:\"wir-w\u00fcrden-andrej-jederzeit-weiterempfehlen\";s:7:\"content\";s:44:\"Wir w\u00fcrden Andrej jederzeit weiterempfehlen\";s:5:\"depth\";i:3;}i:45;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:20:\"sie-inspirieren-mich\";s:7:\"content\";s:21:\"Sie inspirieren mich!\";s:5:\"depth\";i:3;}i:46;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:88:\"von-der-buchung-bis-zur-bild\u00fcbergabe-hochzeitsfotograf-langwieder-see-so-einfach-ist-es\";s:7:\"content\";s:94:\"Von der Buchung bis zur Bild\u00fcbergabe: Hochzeitsfotograf Langwieder See \u2013 So einfach ist es!\";s:5:\"depth\";i:2;}i:47;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:2:\"15\";s:7:\"content\";s:2:\"15\";s:5:\"depth\";i:3;}i:48;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:3:\"500\";s:7:\"content\";s:3:\"500\";s:5:\"depth\";i:3;}i:49;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:3:\"198\";s:7:\"content\";s:3:\"198\";s:5:\"depth\";i:3;}i:50;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:5:\"21600\";s:7:\"content\";s:6:\"21.600\";s:5:\"depth\";i:3;}i:51;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:45:\"suchen-sie-einen-fotografen-am-langwieder-see\";s:7:\"content\";s:46:\"Suchen Sie einen Fotografen am Langwieder See?\";s:5:\"depth\";i:2;}i:52;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:16:\"andrej-nikolajew\";s:7:\"content\";s:16:\"Andrej Nikolajew\";s:5:\"depth\";i:3;}i:53;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:15:\"kontaktformular\";s:7:\"content\";s:15:\"Kontaktformular\";s:5:\"depth\";i:2;}i:54;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:45:\"instagram-wl-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:50:\"Instagram W&L \u2013 Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:2;}i:55;a:4:{s:5:\"level\";i:2;s:2:\"id\";s:68:\"tipps-f\u00fcr-unvergessliche-hochzeitsfotos-von-fotograf-langwieder-see\";s:7:\"content\";s:68:\"Tipps f\u00fcr unvergessliche Hochzeitsfotos von fotograf Langwieder See\";s:5:\"depth\";i:2;}i:56;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:12:\"vorbereitung\";s:7:\"content\";s:12:\"Vorbereitung\";s:5:\"depth\";i:3;}i:57;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:60:\"profi-fotografen-ausw\u00e4hlen-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:62:\"Profi-Fotografen ausw\u00e4hlen | Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:58;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:67:\"hochzeits-timeline-erstellen-profi-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:69:\"Hochzeits-Timeline erstellen | Profi-Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:59;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:64:\"details-besprechen-renommierter-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:66:\"Details besprechen | Renommierter Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:60;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:71:\"brautkleid-accessoires-hochzeitsfotograf-mit-stilgef\u00fchl-langwieder-see\";s:7:\"content\";s:75:\"Brautkleid & Accessoires | Hochzeitsfotograf mit Stilgef\u00fchl Langwieder See\";s:5:\"depth\";i:3;}i:61;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:54:\"brautstyling-moderner-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:56:\"Brautstyling | Moderner Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:62;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:15:\"am-hochzeitstag\";s:7:\"content\";s:15:\"Am Hochzeitstag\";s:5:\"depth\";i:3;}i:63;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:63:\"entspannt-bleiben-hochzeitsfotograf-mit-know-how-langwieder-see\";s:7:\"content\";s:65:\"Entspannt bleiben | Hochzeitsfotograf mit Know-how Langwieder See\";s:5:\"depth\";i:3;}i:64;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:57:\"gute-laune-hochzeitsfotograf-mit-erfahrung-langwieder-see\";s:7:\"content\";s:59:\"Gute Laune | Hochzeitsfotograf mit Erfahrung Langwieder See\";s:5:\"depth\";i:3;}i:65;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:56:\"nat\u00fcrlichkeit-bewahren-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:58:\"Nat\u00fcrlichkeit bewahren | Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:66;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:26:\"w\u00e4hrend-der-fotoshootings\";s:7:\"content\";s:26:\"W\u00e4hrend der Fotoshootings\";s:5:\"depth\";i:3;}i:67;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:73:\"verschiedene-locations-nutzen-erfahrener-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:75:\"Verschiedene Locations nutzen | Erfahrener Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:68;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:70:\"gruppenfotos-organisieren-innovativer-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:72:\"Gruppenfotos organisieren | Innovativer Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:69;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:58:\"paarfotos-k\u00fcnstlerischer-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:60:\"Paarfotos | K\u00fcnstlerischer Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:70;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:48:\"details-momente-brautpaarfotograf-langwieder-see\";s:7:\"content\";s:52:\"Details & Momente | Brautpaarfotograf Langwieder See\";s:5:\"depth\";i:3;}i:71;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:63:\"spa\u00df-emotionen-qualifizierter-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:67:\"Spa\u00df & Emotionen | Qualifizierter Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:72;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:39:\"ihr-hochzeitsfotograf-im-langwieder-see\";s:7:\"content\";s:39:\"Ihr Hochzeitsfotograf im Langwieder See\";s:5:\"depth\";i:3;}i:73;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:17:\"tipps-f\u00fcr-posing\";s:7:\"content\";s:17:\"Tipps f\u00fcr Posing\";s:5:\"depth\";i:3;}i:74;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:68:\"sich-aufrichten-hochzeitsfotograf-mit-berufserfahrung-langwieder-see\";s:7:\"content\";s:70:\"Sich aufrichten | Hochzeitsfotograf mit Berufserfahrung Langwieder See\";s:5:\"depth\";i:3;}i:75;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:55:\"winkel-professioneller-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:57:\"Winkel | Professioneller Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:76;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:65:\"entspanne-dein-gesicht-kreativer-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:67:\"Entspanne dein Gesicht | Kreativer Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:77;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:59:\"selbstvertrauen-erfahrener-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:61:\"Selbstvertrauen | Erfahrener Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:78;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:54:\"sei-locker-stilvoller-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:56:\"Sei locker | Stilvoller Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}i:79;a:4:{s:5:\"level\";i:3;s:2:\"id\";s:42:\"hab-spa\u00df-hochzeitsfotograf-langwieder-see\";s:7:\"content\";s:45:\"Hab Spa\u00df! | Hochzeitsfotograf Langwieder See\";s:5:\"depth\";i:3;}}}"],"_oembed_4a890161fdd3ee81ba8a0203a7836428":["<iframe title=\"\u25b6\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/tidiBU7Dwu4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_4a890161fdd3ee81ba8a0203a7836428":["1714639073"],"_oembed_02ed81e03e66480c30193b5ea1ba25ce":["<iframe title=\"\u25b6\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/tidiBU7Dwu4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_02ed81e03e66480c30193b5ea1ba25ce":["1715258933"],"_uag_page_assets":["a:9:{s:3:\"css\";s:190377:\".uagb-block-6cba958f.uagb-section__wrap{padding-top: 50px;padding-bottom: 20px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;border-style: none;margin-right: 0px;margin-left: 0px;max-width: 100%;}.uagb-block-6cba958f > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-6cba958f > .uagb-section__inner-wrap{max-width: 1200px;}.uagb-block-6cba958f.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-6cba958f > .uagb-section__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-28258681.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-28258681.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-28258681.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-28258681.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-28258681.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-28258681 .uagb-heading-text{margin-bottom: 15px;}.uagb-block-3a853490.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-3a853490 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-3a853490 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-3a853490 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-3a853490 .uagb-column__wrap{padding: 10px;}.uagb-block-3a853490 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-3a853490 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-3a853490.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-3a853490 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-3a853490.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8969bd6f.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-8969bd6f > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-5780da15.uagb-column__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 20px;padding-right: 20px;border-style: none;width: 60%;}.wp-block-uagb-column.uagb-block-5780da15 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-8a1aceaa.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-8a1aceaa.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-8a1aceaa.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8a1aceaa.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8a1aceaa.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8a1aceaa .uagb-heading-text{margin-bottom: 0px;}.wp-block-uagb-column.uagb-block-b0070f0e.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-b0070f0e > .uagb-column__overlay{border-radius:    ;}.uagb-block-0f9a2ccc.wp-block-uagb-table-of-contents{text-align: left;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap ul li{font-size: 15px;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap ol li{font-size: 15px;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap li a:hover{color: var(--ast-global-color-0);}.uagb-block-0f9a2ccc .uagb-toc__list-wrap li a{color: #333333;}.uagb-block-0f9a2ccc .uagb-toc__wrap .uagb-toc__title-wrap{justify-content: left;}.uagb-block-0f9a2ccc .uagb-toc__wrap .uagb-toc__title{justify-content: left;}.uagb-block-0f9a2ccc .uagb-toc__wrap{border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: none;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;background: #ffffff00;width: 100%;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap ol.uagb-toc__list:first-child{margin-left: 20px;margin-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.uagb-block-0f9a2ccc .uagb-toc__list{list-style-type: none !important;}.uagb-block-0f9a2ccc .uagb-toc__list .uagb-toc__list{list-style-type: none !important;}.uagb-block-0f9a2ccc .uagb-toc__title{text-decoration: none;font-size: 15px;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap ol li a{text-decoration: none;font-size: 15px;}.uagb-block-ce3f5011.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-ce3f5011 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-ce3f5011 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-ce3f5011 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-ce3f5011 .uagb-column__wrap{padding: 10px;}.uagb-block-ce3f5011 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-ce3f5011 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-ce3f5011.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-ce3f5011 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-ce3f5011.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-3d8910e0.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-3d8910e0 > .uagb-column__overlay{border-radius:    ;}.uagb-block-8de1164e.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8de1164e.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-8de1164e.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8de1164e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-8de1164e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-8de1164e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-8de1164e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-8de1164e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-8de1164e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-8de1164e.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-8de1164e.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: 708px;}.uagb-block-8de1164e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-8de1164e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-8de1164e.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8de1164e.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e6eb2075.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-e6eb2075 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-e6eb2075 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-e6eb2075 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-e6eb2075 .uagb-column__wrap{padding: 10px;}.uagb-block-e6eb2075 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-e6eb2075 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-e6eb2075.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-e6eb2075 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-e6eb2075.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-1d61e137.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-1d61e137 > .uagb-column__overlay{border-radius:    ;}.uagb-block-37a45a81.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-37a45a81.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-37a45a81.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-37a45a81.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-37a45a81.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-37a45a81.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-37a45a81.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-37a45a81.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-37a45a81.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-37a45a81.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-37a45a81.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: 708px;}.uagb-block-37a45a81.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-37a45a81.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-37a45a81.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-37a45a81.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-00122180.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-00122180 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-00122180 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-00122180 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-00122180 .uagb-column__wrap{padding: 10px;}.uagb-block-00122180 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-00122180 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-00122180.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-00122180 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-00122180.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-92114a47.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-92114a47 > .uagb-column__overlay{border-radius:    ;}.uagb-block-a93e4c7d.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a93e4c7d.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-a93e4c7d.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a93e4c7d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-a93e4c7d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-a93e4c7d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-a93e4c7d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-a93e4c7d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-a93e4c7d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-a93e4c7d.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-a93e4c7d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: 787px;}.uagb-block-a93e4c7d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-a93e4c7d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-a93e4c7d.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a93e4c7d.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-dd5f852c.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-dd5f852c .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-dd5f852c > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-dd5f852c .uagb-column__inner-wrap{padding: 10px;}.uagb-block-dd5f852c .uagb-column__wrap{padding: 10px;}.uagb-block-dd5f852c .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-dd5f852c .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-dd5f852c.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-dd5f852c > .uagb-columns__overlay{border-radius:    ;}.uagb-block-dd5f852c.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-f67ca210.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-f67ca210 > .uagb-column__overlay{border-radius:    ;}.uagb-block-05d8eb34.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-05d8eb34.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-05d8eb34.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-05d8eb34.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-05d8eb34.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-05d8eb34.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-05d8eb34.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-05d8eb34.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-05d8eb34.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-05d8eb34.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-05d8eb34.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: 708px;}.uagb-block-05d8eb34.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-05d8eb34.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-05d8eb34.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-05d8eb34.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-a0b0667a.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-a0b0667a .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-a0b0667a > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-a0b0667a .uagb-column__inner-wrap{padding: 10px;}.uagb-block-a0b0667a .uagb-column__wrap{padding: 10px;}.uagb-block-a0b0667a .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-a0b0667a .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-a0b0667a.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-a0b0667a > .uagb-columns__overlay{border-radius:    ;}.uagb-block-a0b0667a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8c2496ee.uagb-column__wrap{border-style: none;width: 50%;}.wp-block-uagb-column.uagb-block-8c2496ee > .uagb-column__overlay{border-radius:    ;}.uagb-block-e14388f6.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e14388f6.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e14388f6.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e14388f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-e14388f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e14388f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e14388f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e14388f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e14388f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e14388f6.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e14388f6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: 870px;}.uagb-block-e14388f6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e14388f6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e14388f6.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e14388f6.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-column.uagb-block-9f4c48cb.uagb-column__wrap{border-style: none;width: 50%;}.wp-block-uagb-column.uagb-block-9f4c48cb > .uagb-column__overlay{border-radius:    ;}.uagb-block-7cc3264c.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7cc3264c.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-7cc3264c.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7cc3264c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-7cc3264c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-7cc3264c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-7cc3264c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-7cc3264c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-7cc3264c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-7cc3264c.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-7cc3264c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: 870px;}.uagb-block-7cc3264c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-7cc3264c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-7cc3264c.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7cc3264c.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-99497cb5.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-99497cb5 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-99497cb5 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-99497cb5 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-99497cb5 .uagb-column__wrap{padding: 10px;}.uagb-block-99497cb5 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-99497cb5 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-99497cb5.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-99497cb5 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-99497cb5.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-01f5d589.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-01f5d589 > .uagb-column__overlay{border-radius:    ;}.uagb-block-5a114f3d.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5a114f3d.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5a114f3d.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5a114f3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5a114f3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5a114f3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5a114f3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5a114f3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5a114f3d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5a114f3d.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5a114f3d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: px;}.uagb-block-5a114f3d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5a114f3d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5a114f3d.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5a114f3d.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e1ea5dcb.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-e1ea5dcb .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-e1ea5dcb > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-e1ea5dcb .uagb-column__inner-wrap{padding: 10px;}.uagb-block-e1ea5dcb .uagb-column__wrap{padding: 10px;}.uagb-block-e1ea5dcb .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-e1ea5dcb .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-e1ea5dcb.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-e1ea5dcb > .uagb-columns__overlay{border-radius:    ;}.uagb-block-e1ea5dcb.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-f01ec120.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-f01ec120 > .uagb-column__overlay{border-radius:    ;}.uagb-block-23fabeaa.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-23fabeaa.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-23fabeaa.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-23fabeaa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-23fabeaa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-23fabeaa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-23fabeaa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-23fabeaa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-23fabeaa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-23fabeaa.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-23fabeaa.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 1180px;height: 708px;}.uagb-block-23fabeaa.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-23fabeaa.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-23fabeaa.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-23fabeaa.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8fcd27ae.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-8fcd27ae .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-8fcd27ae > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-8fcd27ae .uagb-column__inner-wrap{padding: 10px;}.uagb-block-8fcd27ae .uagb-column__wrap{padding: 10px;}.uagb-block-8fcd27ae .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-8fcd27ae .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-8fcd27ae.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-8fcd27ae > .uagb-columns__overlay{border-radius:    ;}.uagb-block-8fcd27ae.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-ca438040.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-ca438040 > .uagb-column__overlay{border-radius:    ;}.uagb-block-21395a7f.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-21395a7f.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-21395a7f.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-21395a7f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-21395a7f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-21395a7f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-21395a7f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-21395a7f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-21395a7f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-21395a7f.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-21395a7f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: 787px;}.uagb-block-21395a7f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-21395a7f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-21395a7f.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-21395a7f.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-589377f9.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-589377f9 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-589377f9 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-589377f9 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-589377f9 .uagb-column__wrap{padding: 10px;}.uagb-block-589377f9 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-589377f9 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-589377f9.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-589377f9 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-589377f9.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-6f503494.uagb-column__wrap{border-style: none;width: 50%;}.wp-block-uagb-column.uagb-block-6f503494 > .uagb-column__overlay{border-radius:    ;}.uagb-block-af302930.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-af302930.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-af302930.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-af302930.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-af302930.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-af302930.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-af302930.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-af302930.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-af302930.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-af302930.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-af302930.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: 870px;}.uagb-block-af302930.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-af302930.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-af302930.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-af302930.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-column.uagb-block-2580d696.uagb-column__wrap{border-style: none;width: 50%;}.wp-block-uagb-column.uagb-block-2580d696 > .uagb-column__overlay{border-radius:    ;}.uagb-block-6020b9b7.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-6020b9b7.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-6020b9b7.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-6020b9b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-6020b9b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-6020b9b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-6020b9b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-6020b9b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-6020b9b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-6020b9b7.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-6020b9b7.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: 870px;}.uagb-block-6020b9b7.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-6020b9b7.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-6020b9b7.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-6020b9b7.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c53973f4.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-c53973f4 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-c53973f4 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-c53973f4 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-c53973f4 .uagb-column__wrap{padding: 10px;}.uagb-block-c53973f4 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-c53973f4 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-c53973f4.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-c53973f4 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-c53973f4.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-71da0743.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-71da0743 > .uagb-column__overlay{border-radius:    ;}.uagb-block-445d1a62.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-445d1a62.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-445d1a62.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-445d1a62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-445d1a62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-445d1a62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-445d1a62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-445d1a62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-445d1a62.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-445d1a62.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-445d1a62.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: 708px;}.uagb-block-445d1a62.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-445d1a62.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-445d1a62.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-445d1a62.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2da0f1f8.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-2da0f1f8 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-2da0f1f8 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-2da0f1f8 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-2da0f1f8 .uagb-column__wrap{padding: 10px;}.uagb-block-2da0f1f8 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-2da0f1f8 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-2da0f1f8.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-2da0f1f8 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-2da0f1f8.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-c3669a58.uagb-column__wrap{border-style: none;width: 50%;}.wp-block-uagb-column.uagb-block-c3669a58 > .uagb-column__overlay{border-radius:    ;}.uagb-block-85d44d4a.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-85d44d4a.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-85d44d4a.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-85d44d4a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-85d44d4a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-85d44d4a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-85d44d4a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-85d44d4a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-85d44d4a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-85d44d4a.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-85d44d4a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: 870px;}.uagb-block-85d44d4a.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-85d44d4a.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-85d44d4a.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-85d44d4a.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-column.uagb-block-015eb386.uagb-column__wrap{border-style: none;width: 50%;}.wp-block-uagb-column.uagb-block-015eb386 > .uagb-column__overlay{border-radius:    ;}.uagb-block-bc614044.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bc614044.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-bc614044.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bc614044.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-bc614044.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-bc614044.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-bc614044.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-bc614044.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-bc614044.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-bc614044.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-bc614044.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: 870px;}.uagb-block-bc614044.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-bc614044.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-bc614044.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-bc614044.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-183da41b.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-183da41b .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-183da41b > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-183da41b .uagb-column__inner-wrap{padding: 10px;}.uagb-block-183da41b .uagb-column__wrap{padding: 10px;}.uagb-block-183da41b .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-183da41b .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-183da41b.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-183da41b > .uagb-columns__overlay{border-radius:    ;}.uagb-block-183da41b.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-9b173bcb.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-9b173bcb > .uagb-column__overlay{border-radius:    ;}.uagb-block-f033b423.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-f033b423.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-f033b423.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-f033b423.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-f033b423.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-f033b423.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-f033b423.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-f033b423.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-f033b423.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-f033b423.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-f033b423.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: 787px;}.uagb-block-f033b423.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-f033b423.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-f033b423.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-f033b423.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-08249a1d.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-08249a1d .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-08249a1d > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-08249a1d .uagb-column__inner-wrap{padding: 10px;}.uagb-block-08249a1d .uagb-column__wrap{padding: 10px;}.uagb-block-08249a1d .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-08249a1d .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-08249a1d.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-08249a1d > .uagb-columns__overlay{border-radius:    ;}.uagb-block-08249a1d.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8bdfcf93.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-8bdfcf93 > .uagb-column__overlay{border-radius:    ;}.uagb-block-9d4235e1.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d4235e1.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-9d4235e1.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d4235e1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-9d4235e1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-9d4235e1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-9d4235e1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-9d4235e1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-9d4235e1.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-9d4235e1.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-9d4235e1.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: 708px;}.uagb-block-9d4235e1.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-9d4235e1.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-9d4235e1.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9d4235e1.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5d07860f.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-5d07860f .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-5d07860f > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-5d07860f .uagb-column__inner-wrap{padding: 10px;}.uagb-block-5d07860f .uagb-column__wrap{padding: 10px;}.uagb-block-5d07860f .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-5d07860f .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-5d07860f.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-5d07860f > .uagb-columns__overlay{border-radius:    ;}.uagb-block-5d07860f.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-7cba0af0.uagb-column__wrap{border-style: none;width: 100%;}.wp-block-uagb-column.uagb-block-7cba0af0 > .uagb-column__overlay{border-radius:    ;}.uagb-block-8e06d8b2.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8e06d8b2.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-8e06d8b2.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8e06d8b2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-8e06d8b2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-8e06d8b2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-8e06d8b2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-8e06d8b2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-8e06d8b2.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-8e06d8b2.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-8e06d8b2.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: 787px;}.uagb-block-8e06d8b2.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-8e06d8b2.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-8e06d8b2.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8e06d8b2.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-fccfb223 .uagb-ss-repeater span.uagb-ss__link{color: #3a3a3a;}.uagb-block-fccfb223 .uagb-ss-repeater a.uagb-ss__link{color: #3a3a3a;}.uagb-block-fccfb223 .uagb-ss-repeater span.uagb-ss__link svg{fill: #3a3a3a;}.uagb-block-fccfb223 .uagb-ss-repeater a.uagb-ss__link svg{fill: #3a3a3a;}.uagb-block-fccfb223.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 5px;margin-bottom: 5px;}.uagb-block-fccfb223.uagb-social-share__layout-vertical .uagb-ss__link{padding: 10px;}.uagb-block-fccfb223.uagb-social-share__layout-horizontal .uagb-ss__link{padding: 10px;}.uagb-block-fccfb223.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 5px;margin-right: 5px;}.uagb-block-fccfb223 .wp-block-uagb-social-share-child {border-radius: 0px;}.uagb-block-fccfb223 .uagb-ss__source-wrap{width: 30px;}.uagb-block-fccfb223 .uagb-ss__source-wrap svg{width: 30px;height: 30px;}.uagb-block-fccfb223 .uagb-ss__source-image{width: 30px;}.uagb-block-fccfb223 .uagb-ss__source-icon{width: 30px;height: 30px;font-size: 30px;}.uagb-block-fccfb223.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.uagb-block-71408164.uagb-ss-repeater span.uagb-ss__link{color: #bd081c;}.uagb-block-71408164.uagb-ss-repeater a.uagb-ss__link{color: #bd081c;}.uagb-block-71408164.uagb-ss-repeater span.uagb-ss__link svg{fill: #bd081c;}.uagb-block-71408164.uagb-ss-repeater a.uagb-ss__link svg{fill: #bd081c;}.uagb-block-58e2cd2d.uagb-ss-repeater span.uagb-ss__link{color: #3b5998;}.uagb-block-58e2cd2d.uagb-ss-repeater a.uagb-ss__link{color: #3b5998;}.uagb-block-58e2cd2d.uagb-ss-repeater span.uagb-ss__link svg{fill: #3b5998;}.uagb-block-58e2cd2d.uagb-ss-repeater a.uagb-ss__link svg{fill: #3b5998;}.uagb-block-d7381ce6.uagb-ss-repeater span.uagb-ss__link{color: #55acee;}.uagb-block-d7381ce6.uagb-ss-repeater a.uagb-ss__link{color: #55acee;}.uagb-block-d7381ce6.uagb-ss-repeater span.uagb-ss__link svg{fill: #55acee;}.uagb-block-d7381ce6.uagb-ss-repeater a.uagb-ss__link svg{fill: #55acee;}.uagb-block-809d6f81.uagb-ss-repeater span.uagb-ss__link{color: #0077b5;}.uagb-block-809d6f81.uagb-ss-repeater a.uagb-ss__link{color: #0077b5;}.uagb-block-809d6f81.uagb-ss-repeater span.uagb-ss__link svg{fill: #0077b5;}.uagb-block-809d6f81.uagb-ss-repeater a.uagb-ss__link svg{fill: #0077b5;}.uagb-block-0d44a065.uagb-section__wrap{padding-top: 50px;padding-bottom: 50px;padding-left: 0px;padding-right: 0px;margin-top: 50px;margin-bottom: 0px;border-style: none;margin-right: 0px;margin-left: 0px;max-width: 100%;}.uagb-block-0d44a065 > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-0d44a065 > .uagb-section__inner-wrap{max-width: 1200px;}.uagb-block-0d44a065.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-0d44a065 > .uagb-section__overlay{background-color: #f9f7f6;border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-4d5691ef.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-4d5691ef.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-4d5691ef.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4d5691ef.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4d5691ef.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4d5691ef .uagb-heading-text{margin-bottom: 15px;}.uagb-block-23db181a.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-23db181a .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-23db181a > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-23db181a .uagb-column__inner-wrap{padding: 10px;}.uagb-block-23db181a .uagb-column__wrap{padding: 10px;}.uagb-block-23db181a .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-23db181a .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-23db181a.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-23db181a > .uagb-columns__overlay{border-radius:    ;}.uagb-block-23db181a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-518ce70a.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-518ce70a > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-1a2fff83.uagb-column__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 20px;padding-right: 20px;border-style: none;width: 60%;}.wp-block-uagb-column.uagb-block-1a2fff83 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-1448e84b.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-1448e84b > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-ff8335b5.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ff8335b5.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ff8335b5.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ff8335b5.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ff8335b5.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ff8335b5 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-4b6b96b7.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-4b6b96b7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-4b6b96b7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4b6b96b7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4b6b96b7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4b6b96b7 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c54b98db.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c54b98db.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c54b98db.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c54b98db.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c54b98db.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c54b98db .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-22dac786.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-22dac786.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-22dac786.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-22dac786.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-22dac786.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-22dac786 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d8151400.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-d8151400.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-d8151400.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d8151400.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d8151400.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d8151400 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e11abd9d.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e11abd9d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e11abd9d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e11abd9d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e11abd9d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e11abd9d .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-00233554.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-00233554.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-00233554.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-00233554.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-00233554.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-00233554 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-02fd17f9.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-02fd17f9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-02fd17f9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-02fd17f9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-02fd17f9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-02fd17f9 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ea2a6bdc.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ea2a6bdc.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ea2a6bdc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ea2a6bdc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ea2a6bdc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ea2a6bdc .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-34b95a6e.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-34b95a6e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-34b95a6e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-34b95a6e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-34b95a6e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-34b95a6e .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-12c6710c.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-12c6710c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-12c6710c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12c6710c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12c6710c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12c6710c .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c173d735.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c173d735.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c173d735.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c173d735.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c173d735.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c173d735 .uagb-heading-text{margin-bottom: 15px;}.uagb-block-8d2c8d2f.uagb-section__wrap{padding-top: 50px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;border-style: none;margin-right: 0px;margin-left: 0px;max-width: 100%;}.uagb-block-8d2c8d2f > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-8d2c8d2f > .uagb-section__inner-wrap{max-width: 1200px;}.uagb-block-8d2c8d2f.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-8d2c8d2f > .uagb-section__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-ba89df19.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-ba89df19.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ba89df19.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ba89df19.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ba89df19.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ba89df19 .uagb-heading-text{margin-bottom: 15px;}.uagb-block-89070a25.uagb-section__wrap{padding-top: 50px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;border-style: none;margin-right: 0px;margin-left: 0px;max-width: 100%;}.uagb-block-89070a25 > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-89070a25 > .uagb-section__inner-wrap{max-width: 1200px;}.uagb-block-89070a25.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-89070a25 > .uagb-section__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-702b6753.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-702b6753.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-702b6753.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-702b6753.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-702b6753.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-702b6753 .uagb-heading-text{margin-bottom: 15px;}.uagb-block-2d8fb6c8.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-2d8fb6c8 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-2d8fb6c8 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-2d8fb6c8 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-2d8fb6c8 .uagb-column__wrap{padding: 10px;}.uagb-block-2d8fb6c8 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-2d8fb6c8 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-2d8fb6c8.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-2d8fb6c8 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-2d8fb6c8.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-b78e985d.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-b78e985d > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-9bbc0ec6.uagb-column__wrap{border-style: none;width: 60%;}.wp-block-uagb-column.uagb-block-9bbc0ec6 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-b2add8f1.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-b2add8f1 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-6895325c.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6895325c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6895325c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6895325c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6895325c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6895325c .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0bf0d4a8.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0bf0d4a8.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0bf0d4a8.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0bf0d4a8.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0bf0d4a8.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0bf0d4a8 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-cac5f992.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-cac5f992.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-cac5f992.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-cac5f992.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-cac5f992.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-cac5f992 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ee7f1338.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ee7f1338.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ee7f1338.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ee7f1338.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ee7f1338.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ee7f1338 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-4d2a3361.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-4d2a3361.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-4d2a3361.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4d2a3361.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4d2a3361.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4d2a3361 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-73311da9.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-73311da9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-73311da9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-73311da9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-73311da9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-73311da9 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f5012ece.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f5012ece.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f5012ece.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f5012ece.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f5012ece.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f5012ece .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-de14c2cf.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 20px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-de14c2cf.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-de14c2cf.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-de14c2cf.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-de14c2cf.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-de14c2cf .uagb-heading-text{margin-bottom: 15px;}.uagb-block-3dcbfd0b.uagb-section__wrap{padding-top: 50px;padding-bottom: 50px;padding-left: 0px;padding-right: 0px;margin-top: 50px;margin-bottom: 0px;border-style: none;margin-right: 0px;margin-left: 0px;max-width: 100%;}.uagb-block-3dcbfd0b > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-3dcbfd0b > .uagb-section__inner-wrap{max-width: 1200px;}.uagb-block-3dcbfd0b.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-3dcbfd0b > .uagb-section__overlay{background-color: #f4f0ed;border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-b1c1270e.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-b1c1270e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b1c1270e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b1c1270e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b1c1270e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b1c1270e .uagb-heading-text{margin-bottom: 15px;}.uagb-block-277b889b.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-277b889b .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-277b889b > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-277b889b .uagb-column__inner-wrap{padding: 10px;}.uagb-block-277b889b .uagb-column__wrap{padding: 10px;}.uagb-block-277b889b .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-277b889b .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-277b889b.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-277b889b > .uagb-columns__overlay{border-radius:    ;}.uagb-block-277b889b.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-78bffa72.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-78bffa72 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-17a51565.uagb-column__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 20px;padding-right: 20px;border-style: none;width: 60%;}.wp-block-uagb-column.uagb-block-17a51565 > .uagb-column__overlay{border-radius:    ;}.uagb-block-c4de3121 p.uagb-team__desc{font-size: 22px;margin-bottom: 0px;margin-top: 0px;}.uagb-block-c4de3121 .uagb-team__prefix{font-size: 15px;}.uagb-block-c4de3121 .uagb-team__social-icon a{color: #333;font-size: 20px;width: 20px;height: 20px;line-height: 20px;}.uagb-block-c4de3121 .uagb-team__social-icon svg{fill: #333;width: 20px;height: 20px;}.uagb-block-c4de3121 .uagb-team__social-icon:hover a{color: #0274be;}.uagb-block-c4de3121 .uagb-team__social-icon:hover svg{fill: #0274be;}.uagb-block-c4de3121.uagb-team__image-position-left .uagb-team__social-icon{margin-right: 20px;margin-left: 0px;}.uagb-block-c4de3121.uagb-team__image-position-right .uagb-team__social-icon{margin-left: 20px;margin-right: 0px;}.uagb-block-c4de3121.uagb-team__image-position-above.uagb-team__align-center .uagb-team__social-icon{margin-right: 10px;margin-left: 10px;}.uagb-block-c4de3121.uagb-team__image-position-above.uagb-team__align-left .uagb-team__social-icon{margin-right: 20px;margin-left: 0px;}.uagb-block-c4de3121.uagb-team__image-position-above.uagb-team__align-right .uagb-team__social-icon{margin-left: 20px;margin-right: 0px;}.uagb-block-c4de3121 .uagb-team__image-wrap{margin-top: 0px;margin-bottom: 0px;margin-left: auto;margin-right: auto;width: 320px;height: 320px;}.uagb-block-c4de3121.uagb-team__image-position-left > img{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;width: 320px;height: 320px;}.uagb-block-c4de3121.uagb-team__image-position-right .uagb-team__content + img{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;width: 320px;height: 320px;}.uagb-block-c4de3121.uagb-team__image-position-above img{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;width: 320px;height: 320px;}.uagb-block-c4de3121 .uagb-team__social-list{justify-content: center;}.uagb-block-c4de3121 h3.uagb-team__title{font-size: 30px;line-height: 2em;margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-473a530a.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-473a530a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-473a530a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-473a530a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-473a530a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-473a530a .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-77f44068.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-77f44068.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-77f44068.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-77f44068.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-77f44068.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-77f44068 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-980dae1a.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-980dae1a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-980dae1a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-980dae1a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-980dae1a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-980dae1a .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b90c3bdc.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-b90c3bdc.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b90c3bdc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b90c3bdc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b90c3bdc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b90c3bdc .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0b9299ec.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-0b9299ec.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0b9299ec.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0b9299ec.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0b9299ec.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0b9299ec .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c5730d29.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-c5730d29.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c5730d29.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c5730d29.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c5730d29.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c5730d29 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-column.uagb-block-ec1328dc.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-ec1328dc > .uagb-column__overlay{border-radius:    ;}.uagb-block-6b718ec7.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 20px;padding-bottom: 40px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-6b718ec7 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-6b718ec7 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-6b718ec7 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-6b718ec7 .uagb-column__wrap{padding: 10px;}.uagb-block-6b718ec7 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-6b718ec7 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-6b718ec7.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-6b718ec7 > .uagb-columns__overlay{background-color: #000000;border-radius:    ;}.uagb-block-6b718ec7.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-706e2ead.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-706e2ead > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-08efe18e.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-08efe18e.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-08efe18e.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-08efe18e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-08efe18e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-08efe18e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-08efe18e .uagb-heading-text{font-size: 89.6px;}.wp-block-uagb-advanced-heading.uagb-block-08efe18e .uagb-desc-text{font-weight: 400;}.uagb-block-8bbe97ca.uagb-section__wrap{padding-top: 50px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;border-style: none;margin-right: 0px;margin-left: 0px;max-width: 100%;}.uagb-block-8bbe97ca > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-8bbe97ca > .uagb-section__inner-wrap{max-width: 1200px;}.uagb-block-8bbe97ca.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-8bbe97ca > .uagb-section__overlay{background-color: #f9f7f6;border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-c1333379.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-c1333379.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c1333379.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c1333379.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c1333379.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c1333379 .uagb-heading-text{margin-bottom: 15px;}.uagb-block-7a32fb13.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-7a32fb13 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-7a32fb13 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-7a32fb13 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-7a32fb13 .uagb-column__wrap{padding: 10px;}.uagb-block-7a32fb13 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-7a32fb13 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-7a32fb13.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-7a32fb13 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-7a32fb13.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-367a9019.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-367a9019 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-ac384ca8.uagb-column__wrap{border-style: none;width: 60%;}.wp-block-uagb-column.uagb-block-ac384ca8 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-67b1d583.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-67b1d583 > .uagb-column__overlay{border-radius:    ;}.uagb-block-9be43c1a.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 20px;padding-bottom: 40px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-9be43c1a .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-9be43c1a > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-9be43c1a .uagb-column__inner-wrap{padding: 10px;}.uagb-block-9be43c1a .uagb-column__wrap{padding: 10px;}.uagb-block-9be43c1a .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-9be43c1a .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-9be43c1a.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-9be43c1a > .uagb-columns__overlay{background-color: transparent;opacity: 1.01;background-image: linear-gradient(180deg,rgb(188,180,171) 0%,rgb(112,107,102) 100%);border-radius:    ;}.uagb-block-9be43c1a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-b89ae1af.uagb-column__wrap{border-style: none;width: 25%;}.wp-block-uagb-column.uagb-block-b89ae1af > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-338c35ad.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-338c35ad.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-338c35ad.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-338c35ad.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-338c35ad.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-338c35ad.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-338c35ad .uagb-heading-text{font-size: 89.6px;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-338c35ad .uagb-desc-text{font-weight: 400;}.wp-block-uagb-column.uagb-block-dbc69a40.uagb-column__wrap{border-style: none;width: 25%;}.wp-block-uagb-column.uagb-block-dbc69a40 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-87dd7e43.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-87dd7e43.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-87dd7e43.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-87dd7e43.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-87dd7e43.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-87dd7e43.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-87dd7e43 .uagb-heading-text{font-size: 90px;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-87dd7e43 .uagb-desc-text{font-weight: 400;}.wp-block-uagb-column.uagb-block-ff763022.uagb-column__wrap{border-style: none;width: 25%;}.wp-block-uagb-column.uagb-block-ff763022 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-358f8e56.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-358f8e56.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-358f8e56.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-358f8e56.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-358f8e56.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-358f8e56.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-358f8e56 .uagb-heading-text{font-size: 90px;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-358f8e56 .uagb-desc-text{font-weight: 400;}.wp-block-uagb-column.uagb-block-4df8a0f6.uagb-column__wrap{border-style: none;width: 25%;}.wp-block-uagb-column.uagb-block-4df8a0f6 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-38d32911.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-38d32911.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-38d32911.wp-block-uagb-advanced-heading .uagb-desc-text{color: #ffffff;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-38d32911.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-38d32911.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-38d32911.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-38d32911 .uagb-heading-text{font-size: 90px;margin-bottom: 15px;}.uagb-block-f52ed514.uagb-section__wrap{padding-top: 50px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;border-style: none;margin-right: 0px;margin-left: 0px;max-width: 100%;}.uagb-block-f52ed514 > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-f52ed514 > .uagb-section__inner-wrap{max-width: 1200px;}.uagb-block-f52ed514.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-f52ed514 > .uagb-section__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-d408a4cd.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-d408a4cd.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d408a4cd.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d408a4cd.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d408a4cd.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d408a4cd .uagb-heading-text{margin-bottom: 15px;}.uagb-block-7525049a.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-7525049a .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-7525049a > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-7525049a .uagb-column__inner-wrap{padding: 10px;}.uagb-block-7525049a .uagb-column__wrap{padding: 10px;}.uagb-block-7525049a .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-7525049a .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-7525049a.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-7525049a > .uagb-columns__overlay{border-radius:    ;}.uagb-block-7525049a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-d2383292.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-d2383292 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-17d1ba5d.uagb-column__wrap{border-style: none;width: 60%;}.wp-block-uagb-column.uagb-block-17d1ba5d > .uagb-column__overlay{border-radius:    ;}.uagb-block-88e9eeaf p.uagb-team__desc{font-size: 20px;margin-bottom: 30px;margin-top: 30px;}.uagb-block-88e9eeaf .uagb-team__prefix{font-size: 15px;color: #333333;}.uagb-block-88e9eeaf .uagb-team__social-icon a{color: #333333;font-size: 30px;width: 30px;height: 30px;line-height: 30px;}.uagb-block-88e9eeaf .uagb-team__social-icon svg{fill: #333333;width: 30px;height: 30px;}.uagb-block-88e9eeaf .uagb-team__social-icon:hover a{color: #0274be;}.uagb-block-88e9eeaf .uagb-team__social-icon:hover svg{fill: #0274be;}.uagb-block-88e9eeaf.uagb-team__image-position-left .uagb-team__social-icon{margin-right: 20px;margin-left: 0px;}.uagb-block-88e9eeaf.uagb-team__image-position-right .uagb-team__social-icon{margin-left: 20px;margin-right: 0px;}.uagb-block-88e9eeaf.uagb-team__image-position-above.uagb-team__align-center .uagb-team__social-icon{margin-right: 10px;margin-left: 10px;}.uagb-block-88e9eeaf.uagb-team__image-position-above.uagb-team__align-left .uagb-team__social-icon{margin-right: 20px;margin-left: 0px;}.uagb-block-88e9eeaf.uagb-team__image-position-above.uagb-team__align-right .uagb-team__social-icon{margin-left: 20px;margin-right: 0px;}.uagb-block-88e9eeaf .uagb-team__image-wrap{margin-bottom: 15px;margin-left: auto;margin-right: auto;width: 320px;height: 320px;}.uagb-block-88e9eeaf.uagb-team__image-position-left > img{margin-bottom: 15px;margin-left: 20px;margin-right: 20px;width: 320px;height: 320px;}.uagb-block-88e9eeaf.uagb-team__image-position-right .uagb-team__content + img{margin-bottom: 15px;margin-left: 20px;margin-right: 20px;width: 320px;height: 320px;}.uagb-block-88e9eeaf.uagb-team__image-position-above img{margin-bottom: 15px;margin-left: 20px;margin-right: 20px;width: 320px;height: 320px;}.uagb-block-88e9eeaf .uagb-team__social-list{justify-content: center;}.uagb-block-88e9eeaf h3.uagb-team__title{margin-bottom: 0px;}.wp-block-uagb-column.uagb-block-97be4caf.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-97be4caf > .uagb-column__overlay{border-radius:    ;}.uagb-block-01d20fa3.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-01d20fa3 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-01d20fa3 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-01d20fa3 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-01d20fa3 .uagb-column__wrap{padding: 10px;}.uagb-block-01d20fa3 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-01d20fa3 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-01d20fa3.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-01d20fa3 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-01d20fa3.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-600787d0.uagb-column__wrap{border-style: none;width: 33%;}.wp-block-uagb-column.uagb-block-600787d0 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-4320229e.uagb-column__wrap{border-style: none;width: 33%;}.wp-block-uagb-column.uagb-block-4320229e > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-9634b985.uagb-column__wrap{border-style: none;width: 33%;}.wp-block-uagb-column.uagb-block-9634b985 > .uagb-column__overlay{border-radius:    ;}.uagb-block-7ce3ba41.uagb-section__wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;border-style: none;margin-right: 0px;margin-left: 0px;max-width: 100%;}.uagb-block-7ce3ba41 > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-7ce3ba41 > .uagb-section__inner-wrap{max-width: 1200px;}.uagb-block-7ce3ba41.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-7ce3ba41 > .uagb-section__overlay{background-color: #f4f0ed;border-radius:    ;}.uagb-block-c27f6d48.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-c27f6d48 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-c27f6d48 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-c27f6d48 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-c27f6d48 .uagb-column__wrap{padding: 10px;}.uagb-block-c27f6d48 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-c27f6d48 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-c27f6d48.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-c27f6d48 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-c27f6d48.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-418941cd.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-418941cd > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-f7e554f0.uagb-column__wrap{border-style: none;width: 60%;}.wp-block-uagb-column.uagb-block-f7e554f0 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-c4cd187e.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-c4cd187e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c4cd187e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c4cd187e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c4cd187e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c4cd187e .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-column.uagb-block-2456f35d.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-2456f35d > .uagb-column__overlay{border-radius:    ;}.uagb-block-a2a9fde4.uagb-section__wrap{padding-top: 50px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;border-style: none;margin-right: 0px;margin-left: 0px;max-width: 100%;}.uagb-block-a2a9fde4 > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-a2a9fde4 > .uagb-section__inner-wrap{max-width: 1200px;}.uagb-block-a2a9fde4.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-a2a9fde4 > .uagb-section__overlay{background-color: #706b66;border-radius:    ;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action .uagb-cta__title{color: var(--ast-global-color-5);margin-bottom: 10px;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action .uagb-cta__desc{color: var(--ast-global-color-5);margin-bottom: 20px;}.uagb-block-8e8e514c .uagb-cta__align-button-after{margin-left: 10px;}.uagb-block-8e8e514c .uagb-cta__align-button-before{margin-right: 10px;}.uagb-block-8e8e514c .uagb-cta__button-wrapper .uagb-cta-with-svg{font-size: 20px;width: 20px;height: 20px;line-height: 20px;}.uagb-block-8e8e514c .uagb-cta__button-wrapper .uagb-cta__block-link svg{fill: var(--ast-global-color-5);}.uagb-block-8e8e514c.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-right: 10px;font-size: 20px;width: 20px;height: 20px;line-height: 20px;fill: var(--ast-global-color-5);}.uagb-block-8e8e514c.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}.uagb-block-8e8e514c .uagb-cta__content-wrap{text-align: center;}.uagb-block-8e8e514c .uagb-cta__wrap{width: 70%;text-align: center;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action{text-align: center;}.uagb-block-8e8e514c .uagb-cta__buttons{column-gap: 15px;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}.uagb-block-8e8e514c .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 70%;}.uagb-block-8e8e514c .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action  {flex-direction: column;align-items: center;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button{padding-top: 10px;padding-bottom: 10px;padding-left: 14px;padding-right: 14px;align-self: center;height: fit-content;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:hover{background-color: !important;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:focus{background-color: !important;}.uagb-block-8e8e514c .uagb-cta__button-wrapper a.uagb-cta-typeof-button{color: var(--ast-global-color-5);border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-5);border-style: solid;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{color: var(--ast-global-color-5);border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-5);border-style: solid;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{font-size: 20px;}.uagb-block-8e8e514c .uagb-cta__button-wrapper a.uagb-cta__button-link-wrapper{font-size: 20px;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action a.uagb-cta-second__button{text-transform: normal;text-decoration: none;font-size: 14px;}.uagb-block-9a6d37a8.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-9a6d37a8 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-9a6d37a8 > .uagb-columns__inner-wrap{max-width: 100%;}.uagb-block-9a6d37a8 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-9a6d37a8 .uagb-column__wrap{padding: 10px;}.uagb-block-9a6d37a8 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-9a6d37a8 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-9a6d37a8.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-9a6d37a8 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-9a6d37a8.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-6c79ea74.uagb-column__wrap{border-style: none;width: 25%;}.wp-block-uagb-column.uagb-block-6c79ea74 > .uagb-column__overlay{border-radius:    ;}.uagb-block-efee2b46.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-efee2b46.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-efee2b46.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-efee2b46.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-efee2b46.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-efee2b46.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-efee2b46.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-efee2b46.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-efee2b46.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-efee2b46.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-efee2b46.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-efee2b46.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-efee2b46.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-efee2b46.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-efee2b46.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-column.uagb-block-ae1ec349.uagb-column__wrap{border-style: none;width: 25%;}.wp-block-uagb-column.uagb-block-ae1ec349 > .uagb-column__overlay{border-radius:    ;}.uagb-block-b1473385.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b1473385.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-b1473385.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b1473385.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-b1473385.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-b1473385.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-b1473385.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-b1473385.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-b1473385.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-b1473385.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-b1473385.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-b1473385.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-b1473385.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-b1473385.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b1473385.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-column.uagb-block-ddfe5a0c.uagb-column__wrap{border-style: none;width: 25%;}.wp-block-uagb-column.uagb-block-ddfe5a0c > .uagb-column__overlay{border-radius:    ;}.uagb-block-3bb273b6.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3bb273b6.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-3bb273b6.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3bb273b6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-3bb273b6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-3bb273b6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-3bb273b6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-3bb273b6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-3bb273b6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-3bb273b6.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-3bb273b6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-3bb273b6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-3bb273b6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-3bb273b6.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3bb273b6.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-column.uagb-block-69a7d0f2.uagb-column__wrap{border-style: none;width: 25%;}.wp-block-uagb-column.uagb-block-69a7d0f2 > .uagb-column__overlay{border-radius:    ;}.uagb-block-5836722e.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5836722e.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5836722e.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5836722e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5836722e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5836722e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5836722e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5836722e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5836722e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5836722e.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5836722e.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-5836722e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5836722e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5836722e.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5836722e.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-14e36ddc.uagb-section__wrap{padding-top: 50px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;border-style: none;margin-right: 0px;margin-left: 0px;max-width: 100%;}.uagb-block-14e36ddc > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-14e36ddc > .uagb-section__inner-wrap{max-width: 1200px;}.uagb-block-14e36ddc.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-14e36ddc > .uagb-section__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-d04a5abc.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-d04a5abc.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d04a5abc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d04a5abc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d04a5abc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d04a5abc .uagb-heading-text{margin-bottom: 15px;}.uagb-block-3041ad92.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;}.uagb-block-3041ad92 .uagb-columns__video-wrap{opacity: 0.5;}.uagb-block-3041ad92 > .uagb-columns__inner-wrap{max-width: 1200px;}.uagb-block-3041ad92 .uagb-column__inner-wrap{padding: 10px;}.uagb-block-3041ad92 .uagb-column__wrap{padding: 10px;}.uagb-block-3041ad92 .uagb-columns__shape.uagb-columns__shape-top .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-3041ad92 .uagb-columns__shape.uagb-columns__shape-bottom .uagb-columns__shape-fill{fill: rgba(51,51,51,1);}.uagb-block-3041ad92.wp-block-uagb-columns{box-shadow: 0px 0px    ;}.uagb-block-3041ad92 > .uagb-columns__overlay{border-radius:    ;}.uagb-block-3041ad92.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-a76120d3.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-a76120d3 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-column.uagb-block-920e8fd5.uagb-column__wrap{border-style: none;width: 60%;}.wp-block-uagb-column.uagb-block-920e8fd5 > .uagb-column__overlay{border-radius:    ;}.wp-block-uagb-advanced-heading.uagb-block-43d435ab.wp-block-uagb-advanced-heading {text-align: left;padding-top: 50px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-43d435ab.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-43d435ab.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-43d435ab.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-43d435ab.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-43d435ab.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 100%;border-color: #000000;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-43d435ab .uagb-heading-text{margin-bottom: 30px;}.wp-block-uagb-advanced-heading.uagb-block-0bc099e0.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-0bc099e0.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0bc099e0.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0bc099e0.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0bc099e0.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7502289c.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-7502289c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7502289c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7502289c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7502289c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-841b7feb.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-841b7feb.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-841b7feb.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-841b7feb.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-841b7feb.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ad551d26.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-ad551d26.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ad551d26.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ad551d26.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ad551d26.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f8894a30.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-f8894a30.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f8894a30.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f8894a30.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f8894a30.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b803b3d5.wp-block-uagb-advanced-heading {text-align: left;padding-top: 50px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-b803b3d5.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b803b3d5.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b803b3d5.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b803b3d5.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b803b3d5.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 100%;border-color: #000000;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b803b3d5 .uagb-heading-text{margin-bottom: 30px;}.wp-block-uagb-advanced-heading.uagb-block-f28c726d.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-f28c726d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f28c726d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f28c726d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f28c726d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-71bcf0a7.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-71bcf0a7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-71bcf0a7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-71bcf0a7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-71bcf0a7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-548af73b.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-548af73b.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-548af73b.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-548af73b.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-548af73b.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1327dbb4.wp-block-uagb-advanced-heading {text-align: left;padding-top: 50px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-1327dbb4.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1327dbb4.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1327dbb4.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1327dbb4.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1327dbb4.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 100%;border-color: #000000;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1327dbb4 .uagb-heading-text{margin-bottom: 30px;}.wp-block-uagb-advanced-heading.uagb-block-0e5c0890.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-0e5c0890.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0e5c0890.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0e5c0890.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0e5c0890.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5a5e74bc.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-5a5e74bc.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5a5e74bc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5a5e74bc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5a5e74bc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c73be005.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-c73be005.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c73be005.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c73be005.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c73be005.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9ec213d5.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-9ec213d5.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9ec213d5.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9ec213d5.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9ec213d5.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8c83d1fd.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-8c83d1fd.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8c83d1fd.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8c83d1fd.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8c83d1fd.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fe486cbe.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-fe486cbe.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fe486cbe.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fe486cbe.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fe486cbe.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6e4a1b9f.wp-block-uagb-advanced-heading {text-align: left;padding-top: 50px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6e4a1b9f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6e4a1b9f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6e4a1b9f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6e4a1b9f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6e4a1b9f.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 100%;border-color: #000000;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6e4a1b9f .uagb-heading-text{margin-bottom: 30px;}.wp-block-uagb-advanced-heading.uagb-block-77442164.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-77442164.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-77442164.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-77442164.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-77442164.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c2cb94f7.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-c2cb94f7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c2cb94f7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c2cb94f7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c2cb94f7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-441b9f65.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-441b9f65.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-441b9f65.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-441b9f65.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-441b9f65.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-103156b9.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-103156b9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-103156b9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-103156b9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-103156b9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fc601002.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-fc601002.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fc601002.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fc601002.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fc601002.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9328718f.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-9328718f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9328718f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9328718f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9328718f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-column.uagb-block-8d7bab6c.uagb-column__wrap{border-style: none;width: 20%;}.wp-block-uagb-column.uagb-block-8d7bab6c > .uagb-column__overlay{border-radius:    ;} .uagb-block-277cb211 .uagb-google-map__iframe{height: 600px;}@media only screen and (max-width: 976px) {.uagb-block-6cba958f.uagb-section__wrap{border-style: none;}.uagb-block-3a853490.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8969bd6f.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-5780da15.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-b0070f0e.uagb-column__wrap{border-style: none;}.uagb-block-0f9a2ccc .uagb-toc__wrap{border-style: none;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.uagb-block-ce3f5011.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-3d8910e0.uagb-column__wrap{border-style: none;}.uagb-block-8de1164e.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-e6eb2075.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-1d61e137.uagb-column__wrap{border-style: none;}.uagb-block-37a45a81.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-00122180.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-92114a47.uagb-column__wrap{border-style: none;}.uagb-block-a93e4c7d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-dd5f852c.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-f67ca210.uagb-column__wrap{border-style: none;}.uagb-block-05d8eb34.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-a0b0667a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8c2496ee.uagb-column__wrap{border-style: none;}.uagb-block-e14388f6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.wp-block-uagb-column.uagb-block-9f4c48cb.uagb-column__wrap{border-style: none;}.uagb-block-7cc3264c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.uagb-block-99497cb5.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-01f5d589.uagb-column__wrap{border-style: none;}.uagb-block-5a114f3d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e1ea5dcb.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-f01ec120.uagb-column__wrap{border-style: none;}.uagb-block-23fabeaa.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-8fcd27ae.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-ca438040.uagb-column__wrap{border-style: none;}.uagb-block-21395a7f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-589377f9.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-6f503494.uagb-column__wrap{border-style: none;}.uagb-block-af302930.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.wp-block-uagb-column.uagb-block-2580d696.uagb-column__wrap{border-style: none;}.uagb-block-6020b9b7.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.uagb-block-c53973f4.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-71da0743.uagb-column__wrap{border-style: none;}.uagb-block-445d1a62.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-2da0f1f8.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-c3669a58.uagb-column__wrap{border-style: none;}.uagb-block-85d44d4a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.wp-block-uagb-column.uagb-block-015eb386.uagb-column__wrap{border-style: none;}.uagb-block-bc614044.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.uagb-block-183da41b.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-9b173bcb.uagb-column__wrap{border-style: none;}.uagb-block-f033b423.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-08249a1d.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8bdfcf93.uagb-column__wrap{border-style: none;}.uagb-block-9d4235e1.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-5d07860f.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-7cba0af0.uagb-column__wrap{border-style: none;}.uagb-block-8e06d8b2.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-fccfb223.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 5px;margin-bottom: 5px;}.uagb-block-fccfb223.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 5px;margin-right: 5px;}.uagb-block-fccfb223.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.uagb-block-0d44a065.uagb-section__wrap{border-style: none;}.uagb-block-23db181a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-518ce70a.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-1a2fff83.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-1448e84b.uagb-column__wrap{border-style: none;}.uagb-block-8d2c8d2f.uagb-section__wrap{border-style: none;}.uagb-block-89070a25.uagb-section__wrap{border-style: none;}.uagb-block-2d8fb6c8.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-b78e985d.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-9bbc0ec6.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-b2add8f1.uagb-column__wrap{border-style: none;}.uagb-block-3dcbfd0b.uagb-section__wrap{border-style: none;}.uagb-block-277b889b.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-78bffa72.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-17a51565.uagb-column__wrap{border-style: none;}.uagb-block-c4de3121.uagb-team__image-position-left .uagb-team__social-icon{margin-left: 0px;}.uagb-block-c4de3121.uagb-team__image-position-right .uagb-team__social-icon{margin-right: 0px;}.uagb-block-c4de3121.uagb-team__image-position-above.uagb-team__align-center .uagb-team__social-icon{margin-right: 10px;margin-left: 10px;}.uagb-block-c4de3121.uagb-team__image-position-above.uagb-team__align-left .uagb-team__social-icon{margin-left: 0px;}.uagb-block-c4de3121.uagb-team__image-position-above.uagb-team__align-right .uagb-team__social-icon{margin-right: 0px;}.wp-block-uagb-column.uagb-block-ec1328dc.uagb-column__wrap{border-style: none;}.uagb-block-6b718ec7.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-706e2ead.uagb-column__wrap{border-style: none;}.uagb-block-8bbe97ca.uagb-section__wrap{border-style: none;}.uagb-block-7a32fb13.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-367a9019.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-ac384ca8.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-67b1d583.uagb-column__wrap{border-style: none;}.uagb-block-9be43c1a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-b89ae1af.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-dbc69a40.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-ff763022.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-4df8a0f6.uagb-column__wrap{border-style: none;}.uagb-block-f52ed514.uagb-section__wrap{border-style: none;}.uagb-block-7525049a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-d2383292.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-17d1ba5d.uagb-column__wrap{border-style: none;}.uagb-block-88e9eeaf.uagb-team__image-position-left .uagb-team__social-icon{margin-left: 0px;}.uagb-block-88e9eeaf.uagb-team__image-position-right .uagb-team__social-icon{margin-right: 0px;}.uagb-block-88e9eeaf.uagb-team__image-position-above.uagb-team__align-center .uagb-team__social-icon{margin-right: 10px;margin-left: 10px;}.uagb-block-88e9eeaf.uagb-team__image-position-above.uagb-team__align-left .uagb-team__social-icon{margin-left: 0px;}.uagb-block-88e9eeaf.uagb-team__image-position-above.uagb-team__align-right .uagb-team__social-icon{margin-right: 0px;}.wp-block-uagb-column.uagb-block-97be4caf.uagb-column__wrap{border-style: none;}.uagb-block-01d20fa3.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-600787d0.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-4320229e.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-9634b985.uagb-column__wrap{border-style: none;}.uagb-block-7ce3ba41.uagb-section__wrap{border-style: none;}.uagb-block-c27f6d48.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-418941cd.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-f7e554f0.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-2456f35d.uagb-column__wrap{border-style: none;}.uagb-block-a2a9fde4.uagb-section__wrap{border-style: none;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}.uagb-block-8e8e514c.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}.uagb-block-8e8e514c .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-8e8e514c .uagb-cta__wrap{text-align: center;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action  {flex-direction: column;align-items: center;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{border-style: solid;border-color: var(--ast-global-color-5);}.uagb-block-8e8e514c.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-5);}.uagb-block-9a6d37a8.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-6c79ea74.uagb-column__wrap{border-style: none;}.uagb-block-efee2b46.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-column.uagb-block-ae1ec349.uagb-column__wrap{border-style: none;}.uagb-block-b1473385.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-column.uagb-block-ddfe5a0c.uagb-column__wrap{border-style: none;}.uagb-block-3bb273b6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-column.uagb-block-69a7d0f2.uagb-column__wrap{border-style: none;}.uagb-block-5836722e.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-14e36ddc.uagb-section__wrap{border-style: none;}.uagb-block-3041ad92.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-a76120d3.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-920e8fd5.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8d7bab6c.uagb-column__wrap{border-style: none;} .uagb-block-277cb211 .uagb-google-map__iframe{height: 300px;}}@media only screen and (max-width: 767px) {.uagb-block-6cba958f.uagb-section__wrap{border-style: none;}.uagb-block-3a853490.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3a853490.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8969bd6f.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-5780da15.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-b0070f0e.uagb-column__wrap{border-style: none;}.uagb-block-0f9a2ccc .uagb-toc__wrap{border-style: none;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap{column-count: 1;overflow: hidden;text-align: left;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap > ul.uagb-toc__list > li:first-child{padding-top: 0;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap ul.uagb-toc__list:last-child > li:last-child{padding-bottom: 0;}.uagb-block-0f9a2ccc .uagb-toc__list-wrap ol li a{line-height: 1.3em;}.uagb-block-ce3f5011.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-3d8910e0.uagb-column__wrap{border-style: none;}.uagb-block-8de1164e.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-e6eb2075.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-1d61e137.uagb-column__wrap{border-style: none;}.uagb-block-37a45a81.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-00122180.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-92114a47.uagb-column__wrap{border-style: none;}.uagb-block-a93e4c7d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-dd5f852c.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-f67ca210.uagb-column__wrap{border-style: none;}.uagb-block-05d8eb34.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-a0b0667a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8c2496ee.uagb-column__wrap{border-style: none;}.uagb-block-e14388f6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.wp-block-uagb-column.uagb-block-9f4c48cb.uagb-column__wrap{border-style: none;}.uagb-block-7cc3264c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.uagb-block-99497cb5.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-01f5d589.uagb-column__wrap{border-style: none;}.uagb-block-5a114f3d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-e1ea5dcb.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-f01ec120.uagb-column__wrap{border-style: none;}.uagb-block-23fabeaa.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-8fcd27ae.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-ca438040.uagb-column__wrap{border-style: none;}.uagb-block-21395a7f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-589377f9.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-6f503494.uagb-column__wrap{border-style: none;}.uagb-block-af302930.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.wp-block-uagb-column.uagb-block-2580d696.uagb-column__wrap{border-style: none;}.uagb-block-6020b9b7.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.uagb-block-c53973f4.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-71da0743.uagb-column__wrap{border-style: none;}.uagb-block-445d1a62.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-2da0f1f8.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-c3669a58.uagb-column__wrap{border-style: none;}.uagb-block-85d44d4a.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.wp-block-uagb-column.uagb-block-015eb386.uagb-column__wrap{border-style: none;}.uagb-block-bc614044.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 580px;height: auto;}.uagb-block-183da41b.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-9b173bcb.uagb-column__wrap{border-style: none;}.uagb-block-f033b423.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-08249a1d.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8bdfcf93.uagb-column__wrap{border-style: none;}.uagb-block-9d4235e1.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-5d07860f.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-7cba0af0.uagb-column__wrap{border-style: none;}.uagb-block-8e06d8b2.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1180px;height: auto;}.uagb-block-fccfb223.uagb-social-share__layout-vertical .uagb-ss__wrapper{margin-left: 0;margin-right: 0;margin-top: 5px;margin-bottom: 5px;}.uagb-block-fccfb223.uagb-social-share__layout-horizontal .uagb-ss__wrapper{margin-left: 5px;margin-right: 5px;}.uagb-block-fccfb223.uagb-social-share__outer-wrap{justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: center;-ms-flex-align: center;align-items: center;}.uagb-block-0d44a065.uagb-section__wrap{border-style: none;}.uagb-block-23db181a.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-23db181a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-518ce70a.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-1a2fff83.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-1448e84b.uagb-column__wrap{border-style: none;}.uagb-block-8d2c8d2f.uagb-section__wrap{border-style: none;}.uagb-block-89070a25.uagb-section__wrap{border-style: none;}.uagb-block-2d8fb6c8.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-b78e985d.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-9bbc0ec6.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-b2add8f1.uagb-column__wrap{border-style: none;}.uagb-block-3dcbfd0b.uagb-section__wrap{border-style: none;}.uagb-block-277b889b.wp-block-uagb-columns.uagb-columns__wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-277b889b.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-78bffa72.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-17a51565.uagb-column__wrap{border-style: none;}.uagb-block-c4de3121.uagb-team__image-position-left .uagb-team__social-icon{margin-left: 0px;}.uagb-block-c4de3121.uagb-team__image-position-right .uagb-team__social-icon{margin-right: 0px;}.uagb-block-c4de3121.uagb-team__image-position-above.uagb-team__align-center .uagb-team__social-icon{margin-right: 10px;margin-left: 10px;}.uagb-block-c4de3121.uagb-team__image-position-above.uagb-team__align-left .uagb-team__social-icon{margin-left: 0px;}.uagb-block-c4de3121.uagb-team__image-position-above.uagb-team__align-right .uagb-team__social-icon{margin-right: 0px;}.wp-block-uagb-column.uagb-block-ec1328dc.uagb-column__wrap{border-style: none;}.uagb-block-6b718ec7.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-706e2ead.uagb-column__wrap{border-style: none;}.uagb-block-8bbe97ca.uagb-section__wrap{border-style: none;}.uagb-block-7a32fb13.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-367a9019.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-ac384ca8.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-67b1d583.uagb-column__wrap{border-style: none;}.uagb-block-9be43c1a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-b89ae1af.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-dbc69a40.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-ff763022.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-4df8a0f6.uagb-column__wrap{border-style: none;}.uagb-block-f52ed514.uagb-section__wrap{border-style: none;}.uagb-block-7525049a.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-d2383292.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-17d1ba5d.uagb-column__wrap{border-style: none;}.uagb-block-88e9eeaf.uagb-team__image-position-left .uagb-team__social-icon{margin-left: 0px;}.uagb-block-88e9eeaf.uagb-team__image-position-right .uagb-team__social-icon{margin-right: 0px;}.uagb-block-88e9eeaf.uagb-team__image-position-above.uagb-team__align-center .uagb-team__social-icon{margin-right: 10px;margin-left: 10px;}.uagb-block-88e9eeaf.uagb-team__image-position-above.uagb-team__align-left .uagb-team__social-icon{margin-left: 0px;}.uagb-block-88e9eeaf.uagb-team__image-position-above.uagb-team__align-right .uagb-team__social-icon{margin-right: 0px;}.wp-block-uagb-column.uagb-block-97be4caf.uagb-column__wrap{border-style: none;}.uagb-block-01d20fa3.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-600787d0.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-4320229e.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-9634b985.uagb-column__wrap{border-style: none;}.uagb-block-7ce3ba41.uagb-section__wrap{border-style: none;}.uagb-block-c27f6d48.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-418941cd.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-f7e554f0.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-2456f35d.uagb-column__wrap{border-style: none;}.uagb-block-a2a9fde4.uagb-section__wrap{border-style: none;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}.uagb-block-8e8e514c.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}.uagb-block-8e8e514c .uagb-cta__buttons{justify-content: center;}.uagb-block-8e8e514c .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-8e8e514c .uagb-cta__wrap{text-align: center;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action  {flex-direction: column;align-items: center;}.uagb-block-8e8e514c.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{border-style: solid;border-color: var(--ast-global-color-5);}.uagb-block-8e8e514c.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-5);}.uagb-block-9a6d37a8.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-6c79ea74.uagb-column__wrap{border-style: none;}.uagb-block-efee2b46.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-column.uagb-block-ae1ec349.uagb-column__wrap{border-style: none;}.uagb-block-b1473385.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-column.uagb-block-ddfe5a0c.uagb-column__wrap{border-style: none;}.uagb-block-3bb273b6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-column.uagb-block-69a7d0f2.uagb-column__wrap{border-style: none;}.uagb-block-5836722e.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-14e36ddc.uagb-section__wrap{border-style: none;}.uagb-block-3041ad92.uagb-columns__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-a76120d3.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-920e8fd5.uagb-column__wrap{border-style: none;}.wp-block-uagb-column.uagb-block-8d7bab6c.uagb-column__wrap{border-style: none;} .uagb-block-277cb211 .uagb-google-map__iframe{height: 300px;}}.uagb-block-80c34f2d.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-80c34f2d .wp-block-uagb-image__figure{align-items: center;}.uagb-block-80c34f2d.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-80c34f2d.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-80c34f2d.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-80c34f2d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-80c34f2d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-80c34f2d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-80c34f2d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-80c34f2d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-80c34f2d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-80c34f2d.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-80c34f2d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-80c34f2d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-80c34f2d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-80c34f2d.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-80c34f2d.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-80c34f2d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-80c34f2d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-e447270b.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-e447270b .wp-block-uagb-image__figure{align-items: center;}.uagb-block-e447270b.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e447270b.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e447270b.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e447270b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-e447270b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e447270b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e447270b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e447270b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e447270b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e447270b.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e447270b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 147px;height: auto;}.uagb-block-e447270b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e447270b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e447270b.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e447270b.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-e447270b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 147px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-e447270b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 147px;height: auto;}}.uagb-block-e2102df4.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-e2102df4 .wp-block-uagb-image__figure{align-items: center;}.uagb-block-e2102df4.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e2102df4.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e2102df4.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e2102df4.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-e2102df4.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e2102df4.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e2102df4.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e2102df4.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e2102df4.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e2102df4.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e2102df4.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 137px;height: auto;}.uagb-block-e2102df4.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e2102df4.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e2102df4.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e2102df4.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-e2102df4.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 137px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-e2102df4.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 137px;height: auto;}}.uagb-block-cecc8bf4.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-cecc8bf4spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-cecc8bf4 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-cecc8bf4 .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}@media only screen and (max-width: 976px) {.uagb-block-cecc8bf4.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}}@media only screen and (max-width: 767px) {.uagb-block-cecc8bf4.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-cecc8bf4 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-cecc8bf4 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-cecc8bf4+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}}.uagb-block-349ac18f.uagb-section__wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px;margin-bottom: 0px;border-style: none;margin-right: auto;margin-left: auto;max-width: 900px;}.uagb-block-349ac18f > .uagb-section__video-wrap{opacity: 0.5;}.uagb-block-349ac18f > .uagb-section__inner-wrap{max-width: 100%;}.uagb-block-349ac18f.wp-block-uagb-section{box-shadow: 0px 0px    ;}.uagb-block-349ac18f > .uagb-section__overlay{border-radius:    ;}@media only screen and (max-width: 976px) {.uagb-block-349ac18f.uagb-section__wrap{border-style: none;}}@media only screen and (max-width: 767px) {.uagb-block-349ac18f.uagb-section__wrap{border-style: none;}}\";s:2:\"js\";s:1451:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function(){\n\tUAGBTableOfContents._run( {\"mappingHeaders\":[false,true,false,false,false,false],\"scrollToTop\":false,\"makeCollapsible\":false,\"enableCollapsableList\":false,\"initialCollapse\":false,\"markerView\":\"disc\",\"isFrontend\":true,\"initiallyCollapseList\":false}, '.uagb-block-0f9a2ccc' );\n} );\nvar ssLinksParent = document.querySelector( '.uagb-block-fccfb223' );\nssLinksParent?.addEventListener( 'keyup', function ( e ) {\nvar link = e.target.closest( '.uagb-ss__link' );\nif ( link && e.keyCode === 13 ) {\n\thandleSocialLinkClick( link );\n}\n});\n\nssLinksParent?.addEventListener( 'click', function ( e ) {\nvar link = e.target.closest( '.uagb-ss__link' );\nif ( link ) {\n\thandleSocialLinkClick( link );\n}\n});\n\nfunction handleSocialLinkClick( link ) {\nvar social_url = link.dataset.href;\nvar target = \"\";\nif ( social_url == \"mailto:?body=\" ) {\n\ttarget = \"_self\";\n}\nvar request_url = \"\";\nif ( social_url.indexOf(\"\/pin\/create\/link\/?url=\") !== -1 ) {\n\trequest_url = social_url + encodeURIComponent( window.location.href ) + \"&media=\" + 'https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp';\n} else {\n\trequest_url = social_url + encodeURIComponent( window.location.href );\n}\nwindow.open( request_url, target );\n}\n });\";s:18:\"current_block_list\";a:25:{i:0;s:10:\"core\/cover\";i:1;s:14:\"core\/paragraph\";i:2;s:12:\"uagb\/section\";i:3;s:21:\"uagb\/advanced-heading\";i:4;s:12:\"uagb\/columns\";i:5;s:11:\"uagb\/column\";i:6;s:10:\"core\/image\";i:7;s:12:\"core\/buttons\";i:8;s:11:\"core\/button\";i:10;s:22:\"uagb\/table-of-contents\";i:13;s:10:\"uagb\/image\";i:14;s:17:\"uagb\/social-share\";i:15;s:23:\"uagb\/social-share-child\";i:16;s:15:\"core\/media-text\";i:17;s:12:\"core\/columns\";i:18;s:11:\"core\/column\";i:19;s:12:\"core\/heading\";i:20;s:9:\"uagb\/team\";i:21;s:10:\"core\/embed\";i:22;s:18:\"yoast\/how-to-block\";i:23;s:36:\"contact-form-7\/contact-form-selector\";i:25;s:19:\"uagb\/call-to-action\";i:26;s:15:\"uagb\/google-map\";i:27;s:9:\"core\/html\";i:28;s:18:\"uagb\/image-gallery\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1774528264\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:65;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:1;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:53;s:12:\"uagb\/columns\";i:26;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:1;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:21;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:10;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:1;s:23:\"uagb\/social-share-child\";i:4;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:1;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:2;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1776899950"]},"uagb_featured_image_src":{"full":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp",1200,675,false],"thumbnail":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp",128,72,false],"medium":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp",1200,675,false],"medium_large":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-768x432.webp",768,432,true],"large":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp",1200,675,false],"1536x1536":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp",1200,675,false],"2048x2048":["https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-content\/uploads\/sites\/8\/hochzeitsfotograf_in_muenchen-hochzeitsfotografie-muenchen-hochzeitsfotos-hochzeit-muenchen-heiraten-fotoshooting-muenchen-1-jpg.webp",1200,675,false]},"uagb_author_info":{"display_name":"Andrey Nikolaev","author_link":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/author\/andrey-nikolaev\/"},"uagb_comment_info":0,"uagb_excerpt":"Sie inspirieren mich! 15 JAHREHOCHZEITSERFAHRUNG 500 198 GESTALTETEHOCHZEITSFOTOB\u00dcCHER 21.600 AUSBELICHTETEFOTOABZ\u00dcGE","_links":{"self":[{"href":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-json\/wp\/v2\/pages\/12385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-json\/wp\/v2\/comments?post=12385"}],"version-history":[{"count":0,"href":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-json\/wp\/v2\/pages\/12385\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-json\/wp\/v2\/media\/10742"}],"wp:attachment":[{"href":"https:\/\/whiteandlight.com\/hochzeitsfotograf\/wp-json\/wp\/v2\/media?parent=12385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}